{"id":3640,"date":"2019-11-10T13:22:46","date_gmt":"2019-11-10T13:22:46","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-reading\/chinese-reading-li-bai-shi-ci-song-you-ren-song-you-ren\/"},"modified":"2019-11-10T13:22:46","modified_gmt":"2019-11-10T13:22:46","slug":"chinese-reading-li-bai-shi-ci-song-you-ren-song-you-ren","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/fr\/chinese-reading-li-bai-shi-ci-song-you-ren-song-you-ren\/","title":{"rendered":"chinese reading &#8211; \u3010\u674e\u767d\u8bd7\u8bcd\u3011\u2014\u2014 \u9001\u53cb\u4eba\uff08s\u00f2ng y\u01d2u r\u00e9n\uff09"},"content":{"rendered":"<div>s&ograve;ng y\u01d2u r&eacute;n<br \/>  \u9001 \u53cb \u4eba<br \/>  l\u01d0 b&aacute;i<br \/>  \u674e \u767d<br \/>  q\u012bng sh\u0101n h&eacute;ng b\u011bi gu\u014d\uff0cb&aacute;i shu\u01d0 r&agrave;o d\u014dng ch&eacute;ng<br \/>  \u9752 \u5c71 \u6a2a \u5317 \u90ed\uff0c\u767d \u6c34 \u7ed5 \u4e1c \u57ce\u3002<br \/>  c\u01d0 d&igrave; y\u012b w&eacute;i bi&eacute;\uff0cg\u016b p&eacute;ng w&agrave;n l\u01d0 zh\u0113ng<br \/>  \u6b64 \u5730 \u4e00 \u4e3a \u522b\uff0c\u5b64 \u84ec \u4e07 \u91cc \u5f81\u3002<br \/>  f&uacute; y&uacute;n y&oacute;u z\u01d0 y&igrave;\uff0clu&ograve; r&igrave; g&ugrave; r&eacute;n q&iacute;ng<br \/>  \u6d6e \u4e91 \u6e38 \u5b50 \u610f\uff0c\u843d \u65e5 \u6545 \u4eba \u60c5\u3002<br \/>  hu\u012b sh\u01d2u z&igrave; z\u012b q&ugrave;\uff0cxi\u0101o xi\u0101o b\u0101n m\u01ce m&iacute;ng<br \/>  \u6325 \u624b \u81ea \u5179 \u53bb\uff0c\u8427 \u8427 \u73ed \u9a6c \u9e23\u3002<\/p>\n<p>  zh&ugrave; sh&igrave;\uff1a<br \/>  \u6ce8\u91ca\uff1a<br \/>  gu\u014d\uff1ag\u01d4 d&agrave;i z&agrave;i ch&eacute;ng w&agrave;i xi\u016b zh&ugrave; de y\u012b zh\u01d2ng w&agrave;i qi&aacute;ng\u3002<br \/>  \u90ed\uff1a\u53e4\u4ee3\u5728\u57ce\u5916\u4fee\u7b51\u7684\u4e00\u79cd\u5916\u5899\u3002 \u3000\u3000<br \/>  b&aacute;i shu\u01d0\uff1am&iacute;ng j&igrave;ng de shu\u01d0\u3002<br \/>  \u767d\u6c34\uff1a\u660e\u51c0\u7684\u6c34\u3002\u3000<br \/>  y\u012b\uff1azh&ugrave; c&iacute;\uff0cji\u0101 qi&aacute;ng y\u01d4 q&igrave;\u3002<br \/>  \u4e00\uff1a\u52a9\u8bcd\uff0c\u52a0\u5f3a\u8bed\u6c14\u3002<br \/>  w&eacute;i bi&eacute;\uff1af\u0113n bi&eacute;\u3002<br \/>  \u4e3a\u522b\uff1a\u5206\u522b\u3002 \u3000\u3000<br \/>  g\u016b p&eacute;ng\uff1ay&ograve;u m&iacute;ng&ldquo;f\u0113i p&eacute;ng&rdquo;\uff0ck\u016b h&ograve;u g\u0113n du&agrave;n\uff0cch&aacute;ng su&iacute; f\u0113ng f\u0113i xu&aacute;n\u3002zh&egrave; l\u01d0 b\u01d0 y&ugrave; j&iacute; ji\u0101ng g\u016b sh\u0113n yu\u01cen x&iacute;ng de p&eacute;ng y\u01d2u\u3002<br \/>  \u5b64\u84ec\uff1a\u53c8\u540d&ldquo;\u98de\u84ec&rdquo;\uff0c\u67af\u540e\u6839\u65ad\uff0c\u5e38\u968f\u98ce\u98de\u65cb\u3002\u8fd9\u91cc\u6bd4\u55bb\u5373\u5c06\u5b64\u8eab\u8fdc\u884c\u7684\u670b\u53cb\u3002<br \/>  zh\u0113ng\uff1azh\u0113ng t&uacute;\uff0cyu\u01cen x&iacute;ng\u3002<br \/>  \u5f81\uff1a\u5f81\u9014\uff0c\u8fdc\u884c\u3002 \u3000\u3000<br \/>  y&oacute;u z\u01d0\uff1al&iacute; ji\u0101 yu\u01cen y&oacute;u de r&eacute;n\u3002<br \/>  \u6e38\u5b50\uff1a\u79bb\u5bb6\u8fdc\u6e38\u7684\u4eba\u3002 \u3000\u3000<br \/>  z&igrave; z\u012b q&ugrave;\uff1ac&oacute;ng c\u01d0 l&iacute; k\u0101i\u3002<br \/>  \u81ea\u5179\u53bb\uff1a\u4ece\u6b64\u79bb\u5f00\u3002<br \/>  z\u012b\uff1ac\u01d0\uff0cxi&agrave;n z&agrave;i\u3002<br \/>  \u5179\uff1a\u6b64\uff0c\u73b0\u5728\u3002<br \/>  xi\u0101o xi\u0101o\uff1am\u01ce de s\u012b ji&agrave;o sh\u0113ng\u3002<br \/>  \u8427\u8427\uff1a\u9a6c\u7684\u5636\u53eb\u58f0\u3002<br \/>  b\u0101n m\u01ce\uff08zh&ugrave; y&igrave; b&uacute; y&agrave;o xi\u011b ch&eacute;ng &ldquo;b\u0101n m\u01ce&rdquo;\uff09\uff1al&iacute; q&uacute;n de m\u01ce\u3002zh&egrave; l\u01d0 zh\u01d0 z\u01cei r&eacute;n yu\u01cen l&iacute; de m\u01ce\u3002<br \/>  \u73ed\u9a6c\uff08\u6ce8\u610f\u4e0d\u8981\u5199\u6210&ldquo;\u6591\u9a6c&rdquo;\uff09\uff1a\u79bb\u7fa4\u7684\u9a6c\u3002\u8fd9\u91cc\u6307\u8f7d\u4eba\u8fdc\u79bb\u7684\u9a6c\u3002<br \/>  b\u0101n\uff1af\u0113n k\u0101i\uff0cf\u0113n bi&eacute;\u3002 \u3000\u3000<br \/>  \u73ed\uff1a\u5206\u5f00\uff0c\u5206\u522b\u3002<\/p>\n<p>  y&igrave; w&eacute;n\uff1a<br \/>  \u8bd1\u6587\uff1a<br \/>  q\u012bng sh\u0101n h&eacute;ng g&egrave;n z&agrave;i ch&eacute;ng gu\u014d de b\u011bi c&egrave;\uff0cb&aacute;i li&agrave;ng li&agrave;ng de h&eacute; shu\u01d0 hu&aacute;n r&agrave;o z&agrave;i ch&eacute;ng gu\u014d de d\u014dng f\u0101ng\u3002<br \/>  \u9752\u5c71\u6a2a\u4e98\u5728\u57ce\u90ed\u7684\u5317\u4fa7\uff0c\u767d\u4eae\u4eae\u7684\u6cb3\u6c34\u73af\u7ed5\u5728\u57ce\u90ed\u7684\u4e1c\u65b9\u3002\u3000\u3000<br \/>  w\u01d2 men j&iacute; ji\u0101ng z&agrave;i zh&egrave; l\u01d0 l&iacute; bi&eacute;\uff0cn\u01d0 ji&ugrave; y&agrave;o xi&agrave;ng g\u016b f\u0113i de p&eacute;ng c\u01ceo y&iacute; y&agrave;ng t&agrave; sh&agrave;ng w&agrave;n l\u01d0 zh\u0113ng ch&eacute;ng\u3002<br \/>  \u6211\u4eec\u5373\u5c06\u5728\u8fd9\u91cc\u79bb\u522b\uff0c\u4f60\u5c31\u8981\u50cf\u5b64\u98de\u7684\u84ec\u8349\u4e00\u6837\u8e0f\u4e0a\u4e07\u91cc\u5f81\u7a0b\u3002 \u3000\u3000<br \/>  k\u014dng zh\u014dng de b&aacute;i y&uacute;n pi\u0101o f&uacute; b&uacute; d&igrave;ng\uff0cf\u01ceng f&uacute; n\u01d0 x&iacute;ng w&uacute; d&igrave;ng z\u014dng de  x\u012bn x&ugrave;\uff0cj&iacute; ji\u0101ng lu&ograve; sh\u0101n de t&agrave;i y&aacute;ng b&ugrave; r\u011bn ch&eacute;n m&ograve;\uff0cji&ugrave; xi&agrave;ng w\u01d2 du&igrave; n\u01d0  de y\u012b li&agrave;n zh\u012b q&iacute;ng\u3002<br \/>  \u7a7a\u4e2d\u7684\u767d\u4e91\u98d8\u6d6e\u4e0d\u5b9a\uff0c\u4eff\u4f5b\u4f60\u884c\u65e0\u5b9a\u8e2a\u7684\u5fc3\u7eea\uff0c\u5373\u5c06\u843d\u5c71\u7684\u592a\u9633\u4e0d\u5fcd\u6c89\u6ca1\uff0c\u5c31\u50cf\u6211\u5bf9\u4f60\u7684\u4f9d\u604b\u4e4b\u60c5\u3002<br \/>  w\u01d2 men hu\u012b sh\u01d2u g&agrave;o bi&eacute;\uff0cc&oacute;ng zh&egrave; l\u01d0 g&egrave; b\u0113n qi&aacute;n ch&eacute;ng\uff0cli\u01ceng p\u01d0 m\u01ce s&igrave; h\u016b  y\u011b d\u01d2ng d&eacute; zh\u01d4 r&eacute;n de x\u012bn q&iacute;ng\uff0cb&ugrave; r\u011bn l&iacute; bi&eacute; t&oacute;ng b&agrave;n &eacute;r xi\u0101o xi\u0101o  ch&aacute;ng m&iacute;ng\u3002<br \/>  \u6211\u4eec\u6325\u624b\u544a\u522b\uff0c\u4ece\u8fd9\u91cc\u5404\u5954\u524d\u7a0b\uff0c\u4e24\u5339\u9a6c\u4f3c\u4e4e\u4e5f\u61c2\u5f97\u4e3b\u4eba\u7684\u5fc3\u60c5\uff0c\u4e0d\u5fcd\u79bb\u522b\u540c\u4f34\u800c\u8427\u8427\u957f\u9e23\u3002<\/div>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-3852707246\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>s&ograve;ng y\u01d2u r&eacute;n \u9001 \u53cb \u4eba l\u01d0 b&aacute;i \u674e \u767d q\u012bng sh\u0101n h&eacute;ng b\u011bi gu\u014d\uff0cb&aacute;i shu\u01d0 r&agrave;o d\u014dng ch&eacute;ng \u9752<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[41],"class_list":["post-3640","post","type-post","status-publish","format-standard","hentry","category-chinese-reading","tag-chinese-reading"],"views":262,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/posts\/3640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/comments?post=3640"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/posts\/3640\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/media?parent=3640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/categories?post=3640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/fr\/wp-json\/wp\/v2\/tags?post=3640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}