{"id":20,"count":942,"description":"","link":"https:\/\/chinesemoment.com\/mm\/category\/chinese-grammar\/","name":"Chinese Grammar","slug":"chinese-grammar","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}