{"id":14945,"date":"2019-08-28T02:38:25","date_gmt":"2019-08-28T02:38:25","guid":{"rendered":"http:\/\/chinesemoment.com\/spoken-chinese\/the-business-chinese-900-words151-160\/"},"modified":"2019-08-28T02:38:25","modified_gmt":"2019-08-28T02:38:25","slug":"the-business-chinese-900-words151-160","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/mm\/the-business-chinese-900-words151-160\/","title":{"rendered":"The business Chinese 900 words\uff08151-160\uff09"},"content":{"rendered":"<p style=\"text-align: center\">\n<p><div>151.Our clients want a replacement.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n de k&egrave;h&ugrave; y\u0101oqi&uacute; hu&agrave;nhu&ograve;<\/div>\n<div>151.\u6211\u4eec\u7684\u5ba2\u6237\u8981\u6c42\u6362\u8d27\u3002<\/div>\n<\/p>\n<p><div>152.It&#39;s a bit too hard.<\/div>\n<\/p>\n<p><div>zh&egrave;y\u01d2udi\u01cen t&agrave;in&aacute;nle b\u01ce<\/div>\n<div>152.\u8fd9\u6709\u70b9\u592a\u96be\u4e86\u5427\u3002<\/div>\n<\/p>\n<p><div>153.It&#39;s only the background color that&#39;s not identical.<\/div>\n<\/p>\n<p><div>zh&egrave; j\u01d0nj\u01d0n sh&igrave; t&uacute;&agrave;n de d\u01d0s&egrave; b&ugrave;t&oacute;n\u0261 &eacute;ry\u01d0<\/div>\n<div>153.\u8fd9\u4ec5\u4ec5\u662f\u56fe\u6848\u7684\u5e95\u8272\u4e0d\u540c\u800c\u5df2\u3002<\/div>\n<\/p>\n<p><div>154.It sounds like a reasonable solution.<\/div>\n<\/p>\n<p><div>zh&egrave;\u0261e ji\u011bju&eacute; b&agrave;nf\u01ce h&aacute;i b\u01d0ji&agrave;o h&eacute;l\u01d0<\/div>\n<div>154.\u8fd9\u4e2a\u89e3\u51b3\u529e\u6cd5\u8fd8\u6bd4\u8f83\u5408\u7406\u3002<\/div>\n<\/p>\n<p><div>155.You are saying you turn on the computer and see nothing?<\/div>\n<\/p>\n<p><div>n\u01d0de y&igrave;si sh&igrave; n\u01d0b\u01ce j&igrave;su&agrave;nj\u012b d\u01cek\u0101ih&ograve;u sh&eacute;nme y\u011b k&agrave;nb&ugrave;ji&agrave;n<\/div>\n<div>155.\u4f60\u7684\u610f\u601d\u662f\u4f60\u628a\u8ba1\u7b97\u673a\u6253\u5f00\u540e\u4ec0\u4e48\u4e5f\u770b\u4e0d\u89c1\uff1f<\/div>\n<\/p>\n<p><div>156.I would say that you have a larger problem than just the monitor.<\/div>\n<\/p>\n<p><div>w\u01d2xi\u01cen\u0261 n\u01d0de w&egrave;nt&iacute; b\u01d0ji&agrave;od&agrave; b&ugrave;zh\u01d0sh&igrave; xi\u01censh&igrave;q&igrave; de w&egrave;nt&iacute;<\/div>\n<div>156.\u6211\u60f3\u4f60\u7684\u95ee\u9898\u6bd4\u8f83\u5927\uff0c\u4e0d\u53ea\u662f\u663e\u793a\u5668\u7684\u95ee\u9898\u3002<\/div>\n<\/p>\n<p><div>157.Whatever it is, I need this computer to work.<\/div>\n<\/p>\n<p><div>b&ugrave;\u0261u\u01cen sh&igrave; sh&eacute;nme w&egrave;nt&iacute; w\u01d2 y\u0101oqi&uacute; b\u01ce zh&egrave;t&aacute;i j&igrave;su&agrave;nj\u012b xi\u016bh\u01ceo<\/div>\n<div>157.\u4e0d\u7ba1\u662f\u4ec0\u4e48\u95ee\u9898\uff0c\u6211\u8981\u6c42\u628a\u8fd9\u53f0\u8ba1\u7b97\u673a\u4fee\u597d\u3002<\/div>\n<\/p>\n<p><div>158.Is there any way you could bring it in to be looked at?<\/div>\n<\/p>\n<p><div>n\u01d0 y\u01d2um&eacute;iy\u01d2u b&agrave;nf\u01ce b\u01cet\u0101 d&agrave;i\u0261u&ograve;l&aacute;i r&agrave;n\u0261 w\u01d2m&eacute;n k&agrave;ny&iacute;k&agrave;n<\/div>\n<div>158.\u4f60\u6709\u6ca1\u6709\u529e\u6cd5\u628a\u5b83\u5e26\u8fc7\u6765\uff0c\u8ba9\u6211\u4eec\u770b\u4e00\u770b\uff1f<\/div>\n<\/p>\n<p><div>159.If not, our repairman can come to you.<\/div>\n<\/p>\n<p><div>y&agrave;ob&ugrave;r&aacute;n w\u01d2m&eacute;n de w&eacute;ixi\u016b r&eacute;nyu&aacute;n k\u011by\u01d0 sh&agrave;n\u0261 n\u01d0 n&agrave;l\u01d0 q&ugrave;<\/div>\n<div>159.\u8981\u4e0d\u7136\uff0c\u6211\u4eec\u7684\u7ef4\u4fee\u4eba\u5458\u53ef\u4ee5\u4e0a\u4f60\u90a3\u91cc\u53bb\u3002<\/div>\n<\/p>\n<p><div>160.I would prefer if he comes here.<\/div>\n<\/p>\n<p><div>w\u01d2d&agrave;o yu&agrave;ny&igrave; t\u0101&nbsp;q&ugrave;&nbsp;w\u01d2m&eacute;n n&agrave;l\u01d0<\/div>\n<div>160.\u6211\u5012\u613f\u610f\u4ed6\u53bb\u6211\u4eec\u90a3\u91cc\u3002<\/div><\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-3705528193\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>151.Our clients want a replacement.  \tw\u01d2m&eacute;n de k&egrave;h&ugrave; y\u0101oqi&uacute; hu&agrave;nhu&ograve;151.\u6211\u4eec\u7684\u5ba2\u6237\u8981\u6c42\u6362\u8d27\u3002<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2874,2853],"tags":[42],"class_list":["post-14945","post","type-post","status-publish","format-standard","hentry","category-speaking","category-spoken-chinese","tag-business-chinese"],"views":157,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/14945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/comments?post=14945"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/14945\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/media?parent=14945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/categories?post=14945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/tags?post=14945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}