{"id":15246,"date":"2019-12-07T01:59:59","date_gmt":"2019-12-07T01:59:59","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-words-phrases\/chinese-idioms-ru-yu-de-shui-ru-yu-de-shui-2\/"},"modified":"2019-12-07T01:59:59","modified_gmt":"2019-12-07T01:59:59","slug":"chinese-idioms-ru-yu-de-shui-ru-yu-de-shui-2","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/mm\/chinese-idioms-ru-yu-de-shui-ru-yu-de-shui-2\/","title":{"rendered":"Chinese idioms\uff1a\u5982\u9c7c\u5f97\u6c34 R\u00fa y\u00fa d\u00e9 shu\u01d0"},"content":{"rendered":"<p><div>\u6545\u4e8b<\/div>\n<div>Story<\/div>\n<div>S\u0101ngu&oacute; sh&iacute;q\u012b, Li&uacute; b&egrave;i t\u012bngshu\u014d Zh\u016bg\u011b li&agrave;ng sh&igrave; y&iacute; g&egrave; n&aacute;nd&eacute; de r&eacute;nc&aacute;i. W&egrave;ile q\u01d0ng Zh\u016bg\u011b li&agrave;ng b\u0101ngzh&ugrave; z&igrave;j\u01d0 ji&agrave;ng\u014dng l&igrave;y&egrave;, Li&uacute; b&egrave;i c&eacute;ngj\u012bng s\u0101nc&igrave; q\u012bnz&igrave; d&agrave;o Zh\u016bg\u011b li&agrave;ng zh&ugrave; de m&aacute;ol&uacute; b&agrave;if\u01ceng t\u0101. Zh\u016bg\u011b li&agrave;ng k&agrave;n d&agrave;o Li&uacute; b&egrave;i f\u0113ich&aacute;ng ch&eacute;ngk\u011bn, zh\u014dngy&uacute; t&oacute;ngy&igrave; ji&agrave;n Li&uacute; b&egrave;i le. Ji&agrave;nmi&agrave;n zh\u012bh&ograve;u, Li&uacute; b&egrave;i xi&agrave;ng t\u0101 q\u01d0ngji\u0101o le x\u01d4du\u014d zh&igrave;l\u01d0 gu&oacute;ji\u0101 de f\u0101ngf\u01ce. Zh\u016bg\u011b li&agrave;ng b\u0101ng Li&uacute; b&egrave;i z\u01cei x&igrave; f\u0113nx\u012b le d\u0101ngsh&iacute; de q&iacute;ngsh&igrave;, ji&agrave;ny&igrave; Li&uacute; b&egrave;i xi\u0101n zh&agrave;nj&ugrave; J\u012bngzh\u014du, zh&egrave;y&agrave;ng c&aacute;i n&eacute;ng y\u01d2u j\u012bhu&igrave; h&eacute; C&aacute;o c\u0101o\u3001S\u016bn qu&aacute;n d\u01d0ngz&uacute; &eacute;r l&igrave;.<br \/>  \t\u4e09\u56fd\u65f6\u671f\uff0c\u5218\u5907\u542c\u8bf4\u8bf8\u845b\u4eae\u662f\u4e00\u4e2a\u96be\u5f97\u7684\u4eba\u624d\u3002\u4e3a\u4e86\u8bf7\u8bf8\u845b\u4eae\u5e2e\u52a9\u81ea\u5df1\u5efa\u529f\u7acb\u4e1a\uff0c\u5218\u5907\u66fe\u7ecf\u4e09\u6b21\u4eb2\u81ea\u5230\u8bf8\u845b\u4eae\u4f4f\u7684\u8305\u5e90\u62dc\u8bbf\u4ed6\u3002\u8bf8\u845b\u4eae\u770b\u5230\u5218\u5907\u975e\u5e38\u8bda\u6073\uff0c\u7ec8\u4e8e\u540c\u610f\u89c1\u5218\u5907\u4e86\u3002\u89c1\u9762\u4e4b\u540e\uff0c\u5218\u5907\u5411\u4ed6\u8bf7\u6559\u4e86\u8bb8\u591a\u6cbb\u7406\u56fd\u5bb6\u7684\u65b9\u6cd5\u3002\u8bf8\u845b\u4eae\u5e2e\u5218\u5907\u4ed4\u7ec6\u5206\u6790\u4e86\u5f53\u65f6\u7684\u60c5\u52bf\uff0c\u5efa\u8bae\u5218\u5907\u5148\u5360\u636e\u8346\u5dde\uff0c\u8fd9\u6837\u624d\u80fd\u6709\u673a\u4f1a\u548c\u66f9\u64cd\u3001\u5b59\u6743\u9f0e\u8db3\u800c\u7acb\u3002<\/div>\n<div>During the Three Kingdoms Period, Liu Bei heard that Zhuge Liang has exceptional talent. In order to ask him to help set up the country, Liu Bei attempted to meet Zhuge Liang three separate times, in order to ask him to help establish the country. After the failed meetings he finally agreed to meet Liu because of his sincerity. After the meeting, Liu asked him which methods should be used to govern the state. Zhuge Liang helped Liu carefully analyze the current situation and then suggested he first occupy Jingzhou. Only then would it be possible to match the power of Cao Cao and Sun Quan.<\/div>\n<p>  \t<\/p>\n<div>Li&uacute; b&egrave;i h\u011bn x\u012bnsh\u01ceng Zh\u016bg\u011b li&agrave;ng de c&aacute;ihu&aacute;, h&eacute; Zh\u016bg\u011b li&agrave;ng de g\u01cenq&iacute;ng y\u011b zh&uacute;ji&agrave;n ji\u0101 sh\u0113n. T\u0101 g\u0101ox&igrave;ng de g\u0113n bi&eacute;r&eacute;n shu\u014d:&rdquo; W\u01d2 d&eacute; d&agrave;o Zh\u016bg\u011b li&agrave;ng de b\u0101ngzh&ugrave;, ji&ugrave; h\u01ceo xi&agrave;ng y&uacute;&rsquo;&eacute;r d&eacute; d&agrave;o le shu\u01d0 y&iacute;y&agrave;ng.&rdquo;<br \/>  \t\u5218\u5907\u5f88\u6b23\u8d4f\u8bf8\u845b\u4eae\u7684\u624d\u534e\uff0c\u548c\u8bf8\u845b\u4eae\u7684\u611f\u60c5\u4e5f\u9010\u6e10\u52a0\u6df1\u3002\u4ed6\u9ad8\u5174\u5730\u8ddf\u522b\u4eba\u8bf4\uff1a&ldquo;\u6211\u5f97\u5230\u8bf8\u845b\u4eae\u7684\u5e2e\u52a9\uff0c\u5c31\u597d\u50cf\u9c7c\u513f\u5f97\u5230\u4e86\u6c34\u4e00\u6837\u3002&rdquo;<\/div>\n<div>Liu Bei admired Zhuge Liang&rsquo;s talent very much and gradually strengthened their relationship. He happily told others, &ldquo;With the help of Zhuge Liang, I feel like a fish in water&rdquo;.<\/div>\n<p>  \t\u8bcd\u8bed\u6ce8\u91caExplanation<br \/>  \t\u96be\u5f97(n&aacute;nd&eacute;): hard to come by(v.)<br \/>  \t\u5efa\u529f\u7acb\u4e1a( ji&agrave;ng\u014dng l&igrave;y&egrave;): build up establishment(v.)<br \/>  \t\u8305\u5e90( m&aacute;ol&uacute;): thatched cottage(n. )<br \/>  \t\u8bf7\u6559( q\u01d0ngji&agrave;o):consult(v.)<br \/>  \t\u60c5\u52bf( q&iacute;ngsh&igrave;) : state of affairs(n.)<br \/>  \t\u5360\u636e(zh&agrave;nj&ugrave;)\uff1a inhibit(v.)<br \/>  \t\u9f0e\u8db3\u800c\u7acb( d\u01d0ng z&uacute; &eacute;r l&igrave;): standing like a tripod &#8212; a tripartite balance of forces(n.)<\/p>\n<p><div>\u610f\u4e49<\/div>\n<div>Meanings<\/div>\n<div>&ldquo;\u5982\u9c7c\u5f97\u6c34&rdquo;\u672c\u4e49\u6307\u50cf\u9c7c\u5f97\u5230\u6c34\u4e00\u6837\u3002\u6bd4\u55bb\u9047\u5230\u8ddf\u81ea\u5df1\u5341\u5206\u6295\u7f18\u7684\u4eba\u6216\u5bf9\u81ea\u5df1\u5f88\u6709\u5229\u7684\u73af\u5883\u3002<\/div>\n<div>The original meaning of &ldquo;\u5982\u9c7c\u5f97\u6c34&rdquo; is to be like a fish in water. Metaphorically, it refers to individuals who are well suited to each other or to a beneficial environment.<\/div>\n<\/p>\n<p><div>\u4f8b\u53e5<\/div>\n<div>Sentences<\/div>\n<div>1\u3001T\u0101 z&agrave;i xi&agrave;nz&agrave;i de g\u014dngs\u012b g&agrave;n d&eacute; r&uacute;y&uacute; d&eacute;shu\u01d0, d&eacute; d&agrave;o le sh&agrave;ngs\u012b de sh\u01cengsh&iacute; .<br \/>  \t\u4ed6\u5728\u73b0\u5728\u7684\u516c\u53f8\u5e72\u5f97\u5982\u9c7c\u5f97\u6c34\uff0c\u5f97\u5230\u4e86\u4e0a\u53f8\u7684\u8d4f\u8bc6\u3002<\/div>\n<div>He works in the company like a fish in water and was appreciated by his supervisor. <\/div>\n<p>  \t<\/p>\n<div>2\u3001T\u0101 c&oacute;ng xi\u01ceo ji&ugrave; x\u01d0hu\u0101n bi\u01ceoy\u01cen, xi&agrave;nz&agrave;i sh&agrave;ng le di&agrave;ny\u01d0ng xu&eacute;yu&agrave;n ji\u01cenzh&iacute; ji&ugrave; sh&igrave; r&uacute;y&uacute; d&eacute;shu\u01d0.<br \/>  \t\u4ed6\u4ece\u5c0f\u5c31\u559c\u6b22\u8868\u6f14\uff0c\u73b0\u5728\u4e0a\u4e86\u7535\u5f71\u5b66\u9662\u7b80\u76f4\u5c31\u662f\u5982\u9c7c\u5f97\u6c34\u3002<\/div>\n<div>He&rsquo;s liked acting since he was little. Now it is like a fish in water that he went to study at film institute. &nbsp;<\/div>\n<\/p>\n<p>  \t\u539f\u6587\u94fe\u63a5<\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-3527341671\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u6545\u4e8bStory S\u0101ngu&oacute; sh&iacute;q\u012b, Li&uacute; b&egrave;i t\u012bngshu\u014d Zh\u016bg\u011b li&agrave;ng sh&igrave; y&iacute; g&egrave; n&aacute;nd&eacute; de r&eacute;nc&aacute;i. W&egrave;ile q\u01d0ng Zh\u016bg\u011b li&agrave;ng b\u0101ngzh&ugrave; z&igrave;j\u01d0 ji&agrave;ng\u014dng l&igrave;y&egrave;, Li&uacute; b&egrave;i c&eacute;ngj\u012bng s\u0101nc&igrave; q\u012bnz&igrave; d&agrave;o Zh\u016bg\u011b li&agrave;ng zh&ugrave; de m&aacute;ol&uacute; b&agrave;if\u01ceng t\u0101. Zh\u016bg\u011b li&agrave;ng k&agrave;n d&agrave;o Li&uacute; b&egrave;i f\u0113ich&aacute;ng ch&eacute;ngk\u011bn, zh\u014dngy&uacute; t&oacute;ngy&igrave; ji&agrave;n Li&uacute; b&egrave;i le. Ji&agrave;nmi&agrave;n zh\u012bh&ograve;u, Li&uacute; b&egrave;i xi&agrave;ng t\u0101 q\u01d0ngji\u0101o le x\u01d4du\u014d zh&igrave;l\u01d0 gu&oacute;ji\u0101 de f\u0101ngf\u01ce. Zh\u016bg\u011b li&agrave;ng b\u0101ng Li&uacute; b&egrave;i z\u01cei x&igrave; f\u0113nx\u012b le d\u0101ngsh&iacute; de q&iacute;ngsh&igrave;, ji&agrave;ny&igrave; Li&uacute; b&egrave;i xi\u0101n zh&agrave;nj&ugrave; J\u012bngzh\u014du, zh&egrave;y&agrave;ng c&aacute;i n&eacute;ng y\u01d2u j\u012bhu&igrave; h&eacute; C&aacute;o c\u0101o\u3001S\u016bn qu&aacute;n d\u01d0ngz&uacute; &eacute;r l&igrave;.<br \/>\n  \t\u4e09\u56fd\u65f6\u671f\uff0c\u5218\u5907\u542c\u8bf4\u8bf8\u845b\u4eae\u662f\u4e00\u4e2a\u96be\u5f97\u7684\u4eba\u624d\u3002\u4e3a\u4e86\u8bf7\u8bf8\u845b\u4eae\u5e2e\u52a9\u81ea\u5df1\u5efa\u529f\u7acb\u4e1a\uff0c\u5218\u5907\u66fe\u7ecf\u4e09\u6b21\u4eb2\u81ea\u5230\u8bf8\u845b\u4eae\u4f4f\u7684\u8305\u5e90\u62dc\u8bbf\u4ed6\u3002\u8bf8\u845b\u4eae\u770b\u5230\u5218\u5907\u975e\u5e38\u8bda\u6073\uff0c\u7ec8\u4e8e\u540c\u610f\u89c1\u5218\u5907\u4e86\u3002\u89c1\u9762\u4e4b\u540e\uff0c\u5218\u5907\u5411\u4ed6\u8bf7\u6559\u4e86\u8bb8\u591a\u6cbb\u7406\u56fd\u5bb6\u7684\u65b9\u6cd5\u3002\u8bf8\u845b\u4eae\u5e2e\u5218\u5907\u4ed4\u7ec6\u5206\u6790\u4e86\u5f53\u65f6\u7684\u60c5\u52bf\uff0c\u5efa\u8bae\u5218\u5907\u5148\u5360\u636e\u8346\u5dde\uff0c\u8fd9\u6837\u624d\u80fd\u6709\u673a\u4f1a\u548c\u66f9\u64cd\u3001\u5b59\u6743\u9f0e\u8db3\u800c\u7acb\u3002During the Three Kingdoms Period, Liu Bei heard that Zhuge Liang has exceptional talent. In order to ask him to help set up the country, Liu Bei attempted to meet Zhuge Liang three separate times, in order to ask him to help establish the country. After the failed meetings he finally agreed to meet Liu because of his sincerity. After the meeting, Liu asked him which methods should be used to govern the state. Zhuge Liang helped Liu carefully analyze the current situation and then suggested he first occupy Jingzhou. Only then would it be possible to match the power of Cao Cao and Sun Quan.<br \/>\n  \tLi&uacute; b&egrave;i h\u011bn x\u012bnsh\u01ceng Zh\u016bg\u011b li&agrave;ng de c&aacute;ihu&aacute;, h&eacute; Zh\u016bg\u011b li&agrave;ng de g\u01cenq&iacute;ng y\u011b zh&uacute;ji&agrave;n ji\u0101 sh\u0113n. T\u0101 g\u0101ox&igrave;ng de g\u0113n bi&eacute;r&eacute;n shu\u014d:&rdquo; W\u01d2 d&eacute; d&agrave;o Zh\u016bg\u011b li&agrave;ng de b\u0101ngzh&ugrave;, ji&ugrave; h\u01ceo xi&agrave;ng y&uacute;&rsquo;&eacute;r d&eacute; d&agrave;o le shu\u01d0 y&iacute;y&agrave;ng.&rdquo;<br \/>\n  \t\u5218\u5907\u5f88\u6b23\u8d4f\u8bf8\u845b\u4eae\u7684\u624d\u534e\uff0c\u548c\u8bf8\u845b\u4eae\u7684\u611f\u60c5\u4e5f\u9010\u6e10\u52a0\u6df1\u3002\u4ed6\u9ad8\u5174\u5730\u8ddf\u522b\u4eba\u8bf4\uff1a&ldquo;\u6211\u5f97\u5230\u8bf8\u845b\u4eae\u7684\u5e2e\u52a9\uff0c\u5c31\u597d\u50cf\u9c7c\u513f\u5f97\u5230\u4e86\u6c34\u4e00\u6837\u3002&rdquo; Liu Bei admired Zhuge Liang&rsquo;s talent very much and gradually strengthened their relationship. He happily told others, &ldquo;With the help of Zhuge Liang, I feel like a fish in water&rdquo;.<br \/>\n  \t\u8bcd\u8bed\u6ce8\u91caExplanation<br \/>\n  \t\u96be\u5f97(n&aacute;nd&eacute;): hard to come by(v.)<br \/>\n  \t\u5efa\u529f\u7acb\u4e1a( ji&agrave;ng\u014dng l&igrave;y&egrave;): build up establishment(v.)<br \/>\n  \t\u8305\u5e90( m&aacute;ol&uacute;): thatched cottage(n. )<br \/>\n  \t\u8bf7\u6559( q\u01d0ngji&agrave;o):consult(v.)<br \/>\n  \t\u60c5\u52bf( q&iacute;ngsh&igrave;) : state of affairs(n.)<br \/>\n  \t\u5360\u636e(zh&agrave;nj&ugrave;)\uff1a inhibit(v.)<br \/>\n  \t\u9f0e\u8db3\u800c\u7acb( d\u01d0ng z&uacute; &eacute;r l&igrave;): standing like a tripod &#8212; a tripartite balance of forces(n.)<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,2843],"tags":[54],"class_list":["post-15246","post","type-post","status-publish","format-standard","hentry","category-chinese-words-phrases","category-news-vocabulary","tag-chinese-idiom"],"views":169,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/15246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/comments?post=15246"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/15246\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/media?parent=15246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/categories?post=15246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/tags?post=15246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}