{"id":9876,"date":"2019-11-11T19:06:01","date_gmt":"2019-11-11T19:06:01","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-culture\/ke-bi-ji-qi-zhong-wen-mei-ti-fang-tan-kobe-bryant-and-his-interview-with-chinese-media\/"},"modified":"2019-11-11T19:06:01","modified_gmt":"2019-11-11T19:06:01","slug":"ke-bi-ji-qi-zhong-wen-mei-ti-fang-tan-kobe-bryant-and-his-interview-with-chinese-media","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/mm\/ke-bi-ji-qi-zhong-wen-mei-ti-fang-tan-kobe-bryant-and-his-interview-with-chinese-media\/","title":{"rendered":"\u79d1\u6bd4\u53ca\u5176\u4e2d\u6587\u5a92\u4f53\u8bbf\u8c08 Kobe Bryant and His Interview with Chinese Media"},"content":{"rendered":"<div>Kobe is one of the best-known NBA players in China. In 2009, he started  writing his Chinese blog on Sina.com, the most popular internet portal  in China (disclosure: eChineseLearning is also the o<em><\/em>nly Chinese language  provider for Sina). He recently wrote:<br \/>  &quot;\u4e2d\u56fd\u771f\u7684\u662f\u6211\u6700\u559c\u6b22\u7684\u5730\u65b9\u4e4b\u4e00\u3002(<span>zh\u014dng gu&oacute; zh\u0113n de sh&igrave; w\u014f zu&igrave; x\u012d huan de d&igrave; fang zh\u012b y\u012b.<\/span>)&quot;<br \/>  Translation: &quot;China is really one of my favorite places in the world.&quot;<br \/>  During the Beijing Olympic Games in 2009, he told the media:<br \/>  &quot;\u4e2d\u56fd\u5c31\u50cf\u6211\u7684\u7b2c\u4e8c\u6545\u4e61\uff0c\u5728\u8fd9\u513f\u6211\u611f\u5230\u5bbe\u81f3\u5982\u5f52\u3002\u4e2d\u56fd\u4eba\u7684\u70ed\u60c5\u652f\u6301\u603b\u662f\u6fc0\u52b1\u7740\u6211\u6253\u597d\u7bee\u7403\u3002(<span>zh\u014dng  gu&oacute; ji&ugrave; xi&agrave;ng w\u014f de d&igrave; &egrave;r g&ugrave; xi\u0101ng, z&agrave;i zh&egrave; &eacute;r w\u014f g\u0103n d&agrave;o b\u012bn zh&igrave; r&uacute;  gu\u012b. zh\u014dng gu&oacute; r&eacute;n de r&egrave; q&iacute;ng zh\u012b ch&iacute; z\u014fng sh&igrave; j\u012b l&igrave; zhe w\u014f d\u0103 h\u0103o l&aacute;n  qi&uacute;.<\/span>)&quot;<br \/>  Translation: &quot;China is like my second hometown. Here I feel at  home when away from home. The enthusiasm and support of Chinese is  always a huge motivation for me to perform better and better.&quot;<br \/>  <span><br \/>  The following is an interview excerpt between Kobe and CCTV journalist Xiaojie: \t\t  <\/span><br \/>  \u79d1\u6bd4\uff1a\u6211\u7231\u5317\u4eac\uff0c\u7231\u8fd9\u5ea7\u4f1f\u5927\u7684\u57ce\u5e02\uff0c\u5317\u4eac\u4f5c\u4e3a\u4e3b\u4eba\uff0c\u6210\u529f\u6f14\u7ece\u4e86\u5965\u8fd0\u4f1a\uff0c\u6765\u5230\u5317\u4eac\u6211\u975e\u5e38\u5feb\u4e50\u3002<br \/>  <span> \t\t    K\u0113 B\u012d: W\u014f &agrave;i b\u0115i j\u012bng, &agrave;i zh&egrave; zu&ograve; w\u0115i d&agrave; de ch&eacute;ng sh&igrave;, b\u0115i j\u012bng zu&ograve; w&eacute;i zh\u01da r&eacute;n, ch&eacute;ng g\u014dng y\u0103n <br \/>  y&igrave; le &agrave;o y&ugrave;n hu&igrave;, l&aacute;i d&agrave;o b\u0115i j\u012bng w\u014f f\u0113i ch&aacute;ng ku&agrave;i l&egrave;. \t\t  <\/span><br \/>  Kobe: I love Beijing and it is a great city. As the host of the Olympics, Beijing did a successful <br \/>  job. I&#8217;m very happy to be here.<br \/>  \u5c0f\u8282\uff1a\u4f60\u7684\u5bb6\u4eba\u548c\u670b\u53cb\u600e\u4e48\u770b\u5f85\u8fd9\u6b21\u5317\u4eac\u4e4b\u884c\uff1f<br \/>  <span>xi\u0103o ji&eacute;: N\u012d de ji\u0101 r&eacute;n h&eacute; p&eacute;ng you z\u0115n me k&agrave;n d&agrave;i zh&egrave; c&igrave; b\u0115i j\u012bng zh\u012b x&iacute;ng?<\/span><br \/>  Xiaojie: How do your family members and friends think of this trip to Beijing?  <\/p>\n<p>\u79d1\u6bd4\uff1a\u6211\u7684\u5bb6\u4eba\u548c\u670b\u53cb\u5bf9\u6211\u6b64\u6b21\u6765\u5230\u5317\u4eac\u53c2\u52a0\u5965\u8fd0\u4f1a\u611f\u5230\u975e\u5e38\u9a84\u50b2\uff0c\u8fd9\u662f\u6211\u6574\u4e2a\u5bb6\u65cf\u7684\u8363\u8a89\u3002<br \/>  <span> \t\t    K\u0113 B\u012d: W\u014f de ji\u0101 r&eacute;n h&eacute; p&eacute;ng you du&igrave; w\u014f c\u012d c&igrave; l&aacute;i d&agrave;o b\u0115i j\u012bng c\u0101n ji\u0101 &agrave;o y&ugrave;n hu&igrave; g\u0103n d&agrave;o f\u0113i <br \/>  ch&aacute;ng ji\u0101o &agrave;o, zh&egrave; sh&igrave; w\u014f zh\u0115ng g&egrave; ji\u0101 z&uacute; de r&oacute;ng y&ugrave;. \t\t  <\/span><br \/>  Kobe: They are very proud of my taking part in Beijing Olympics. It is the ho<em><\/em>nor of my whole family.<br \/>  \u5c0f\u8282\uff1a\u4f60\u6700\u559c\u6b22\u5403\u4ec0\u4e48\u4e2d\u56fd\u83dc\uff1f<br \/>  <span> \t\t    xi\u0103o ji&eacute;: N\u012d zu&igrave; x\u012d huan ch\u012b sh&eacute;n me zh\u014dng gu&oacute; c&agrave;i? \t\t  <\/span><br \/>  Xiaojie: What is your favorite Chinese dish?<\/p>\n<p>\u79d1\u6bd4\uff1a\u997a\u5b50\uff0c\u975e\u5e38\u597d\u5403\u3002<br \/>  <span>K\u0113 B\u012d: Ji\u0103o zi, f\u0113i ch&aacute;ng h\u0103o ch\u012b.<\/span><br \/>  Kobe: Dumplings, very tasty.<br \/>  \u5c0f\u8282\uff1a\u70e4\u9e2d\u5462\uff1f<br \/>  <span>xi\u0103o ji&eacute;: K\u0103o y\u0101 ne?<\/span><br \/>  Xiaojie: How a<em><\/em>bout Peking duck?<\/p>\n<p>\u79d1\u6bd4\uff1a\u5207\u6210\u8584\u7247\u6cbe\u4e0a\u7cd6\uff0c\u975e\u5e38\u7f8e\u5473\u3002<br \/>  <span>K\u0113 B\u012d: Qi\u0113 ch&eacute;ng b&aacute;o pi&agrave;n zh\u0101n sh&agrave;ng t&aacute;ng, f\u0113i ch&aacute;ng m\u0115i w&egrave;i.<\/span><br \/>  Kobe: If sliced and added sugar, it would be very delicious.<br \/>  \u5c0f\u8282\uff1a\u4f60\u80fd\u7528\u4e2d\u6587\u95ee\u5019\u4e00\u4e0b\u6211\u4eec\u7684\u89c2\u4f17\u5417\uff1f<br \/>  <span>xi\u0103o ji&eacute;: N\u012d n&eacute;ng y&ograve;ng zh\u014dng w&eacute;n w&egrave;n h&ograve;u y&iacute; xi&agrave; w\u014f men de gu\u0101n zh&ograve;ng ma?<\/span><br \/>  Xiaojie: Can you say hello to our audience in Chinese?<\/p>\n<p>\u79d1\u6bd4\uff1a\u65e9\u4e0a\u597d\u3002<br \/>  <span>K\u0113 B\u012d: Z\u0103o shang h\u0103o.<\/span><br \/>  Kobe: Good morning.<\/p>\n<p>  <span>             \u751f\u8bcd (sh\u0113ngc&iacute;) Vocabulary: \t\t  <\/span><br \/>  \u6545\u4e61(<span>g&ugrave;xi\u0101ng<\/span>): <span>n<\/span> hometown<br \/>  \u5bbe\u81f3\u5982\u5f52(<span>b\u012bnzh&igrave;r&uacute;gu\u012b<\/span>): <span>adj <\/span>to feel at home when away from home<br \/>  \u8363\u8a89(<span>r&oacute;ngy&ugrave;<\/span>): <span>n\/v<\/span> honor<br \/>  \u997a\u5b50(<span>ji\u0103ozi<\/span>): <span>n<\/span> dumplings<br \/>  \u5317\u4eac\u70e4\u9e2d(<span>b\u0115ij\u012bng k\u0103oy\u0101<\/span>): <span>n<\/span> Peking duck<br \/>  \u5207(<span>qi\u0113<\/span>): <span>v<\/span> slice, cut<br \/>  \u95ee\u5019(<span>w&egrave;nh&ograve;u<\/span>): <span>v\/n <\/span>say hello to, greet<\/div>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-2636916609\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u79d1\u6bd4\uff1a\u6211\u7684\u5bb6\u4eba\u548c\u670b\u53cb\u5bf9\u6211\u6b64\u6b21\u6765\u5230\u5317\u4eac\u53c2\u52a0\u5965\u8fd0\u4f1a\u611f\u5230\u975e\u5e38\u9a84\u50b2\uff0c\u8fd9\u662f\u6211\u6574\u4e2a\u5bb6\u65cf\u7684\u8363\u8a89\u3002<br \/>\n   \t\t    K\u0113 B\u012d: W\u014f de ji\u0101 r&eacute;n h&eacute; p&eacute;ng you du&igrave; w\u014f c\u012d c&igrave; l&aacute;i d&agrave;o b\u0115i j\u012bng c\u0101n ji\u0101 &agrave;o y&ugrave;n hu&igrave; g\u0103n d&agrave;o f\u0113i<br \/>\n  ch&aacute;ng ji\u0101o &agrave;o, zh&egrave; sh&igrave; w\u014f zh\u0115ng g&egrave; ji\u0101 z&uacute; de r&oacute;ng y&ugrave;.<br \/>\n  Kobe: They are very proud of my taking part in Beijing Olympics. It is the honor of my whole family.<br \/>\n  \u5c0f\u8282\uff1a\u4f60\u6700\u559c\u6b22\u5403\u4ec0\u4e48\u4e2d\u56fd\u83dc\uff1f<br \/>\n   \t\t    xi\u0103o ji&eacute;: N\u012d zu&igrave; x\u012d huan ch\u012b sh&eacute;n me zh\u014dng gu&oacute; c&agrave;i?<br \/>\n  Xiaojie: What is your favorite Chinese dish?<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,2851],"tags":[57,71],"class_list":["post-9876","post","type-post","status-publish","format-standard","hentry","category-chinese-culture","category-people","tag-chinese-language","tag-vocabulary"],"views":218,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/9876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/comments?post=9876"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/posts\/9876\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/media?parent=9876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/categories?post=9876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/mm\/wp-json\/wp\/v2\/tags?post=9876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}