{"id":14947,"date":"2019-08-28T04:49:53","date_gmt":"2019-08-28T04:49:53","guid":{"rendered":"http:\/\/chinesemoment.com\/spoken-chinese\/the-business-chinese-900-words171-180\/"},"modified":"2019-08-28T04:49:53","modified_gmt":"2019-08-28T04:49:53","slug":"the-business-chinese-900-words171-180","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/my\/the-business-chinese-900-words171-180\/","title":{"rendered":"The business Chinese 900 words\uff08171-180\uff09"},"content":{"rendered":"<p style=\"text-align: center\">\n<p><div>171.Then the damage must be caused at somewhere along the line where the goods weren&#39;t handled properly.<\/div>\n<\/p>\n<p><div>n&agrave;me c&aacute;ns\u01d4n y&iacute;d&igrave;n\u0261 sh&igrave;z&agrave;i y&ugrave;nsh\u016b t&uacute;zh\u014dn\u0261 de sh&eacute;nme d&igrave;f\u0101n\u0261 du&igrave; hu&ograve;w&ugrave; ch\u01d4l\u01d0 b&ugrave;tu\u01d2 z&agrave;och&eacute;n\u0261 de<\/div>\n<div>171.\u90a3\u4e48\u6b8b\u635f\u4e00\u5b9a\u662f\u5728\u8fd0\u8f93\u9014\u4e2d\u7684\u4ec0\u4e48\u5730\u65b9\u5bf9\u8d27\u7269\u5904\u7406\u4e0d\u59a5\u9020\u6210\u7684\u3002<\/div>\n<\/p>\n<p><div>172.I would like to present our comments in the following order.<\/div>\n<\/p>\n<p><div>w\u01d2 x\u012bw&agrave;n\u0261 n&eacute;n\u0261 y\u012bzh&agrave;o y&iacute;xi&agrave; de sh&ugrave;nx&ugrave; t&iacute;ch\u016b w\u01d2m&eacute;n de k&agrave;nf\u01ce<\/div>\n<div>172.\u6211\u5e0c\u671b\u80fd\u4f9d\u7167\u4ee5\u4e0b\u7684\u987a\u5e8f\u63d0\u51fa\u6211\u4eec\u7684\u770b\u6cd5\u3002<\/div>\n<\/p>\n<p><div>173.First of all, I will outline the characteristics of our product.<\/div>\n<\/p>\n<p><div>sh\u01d2uxi\u0101n w\u01d2 ji\u0101n\u0261 ji\u01cenl&uuml;&egrave; shu\u014dm&iacute;n\u0261 w\u01d2m&eacute;n sh\u0101n\u0261p\u01d0n de t&egrave;x&igrave;n\u0261<\/div>\n<div>173.\u9996\u5148\u6211\u5c06\u7b80\u7565\u8bf4\u660e\u6211\u4eec\u5546\u54c1\u7684\u7279\u6027\u3002<\/div>\n<\/p>\n<p><div>174.When I present my views on the competitive products, I will refer to the patent situation.<\/div>\n<\/p>\n<p><div>zhu\u0101nl&igrave; de q&iacute;n\u0261ku&agrave;n\u0261 hu&igrave;z&agrave;i shu\u014dm&iacute;n\u0261 j&igrave;n\u0261zh\u0113n\u0261 ch\u01cenp\u01d0n sh&iacute; y&iacute;b&igrave;n\u0261 t&iacute;ch\u016b<\/div>\n<div>174.\u4e13\u5229\u7684\u60c5\u51b5\u4f1a\u5728\u8bf4\u660e\u7ade\u4e89\u4ea7\u54c1\u65f6\u4e00\u5e76\u63d0\u51fa\u3002<\/div>\n<\/p>\n<p><div>175.Please proceed with your presentation.<\/div>\n<\/p>\n<p><div>q\u01d0n\u0261 k\u0101ish\u01d0 n\u01d0de ji\u01cenb&agrave;o<\/div>\n<div>175.\u8bf7\u5f00\u59cb\u4f60\u7684\u7b80\u62a5\u3002<\/div>\n<\/p>\n<p><div>176.Yes, we have been interested in new system.<\/div>\n<\/p>\n<p><div>sh\u01d0de w\u01d2m&eacute;n du&igrave; x\u012bnx&igrave;t\u01d2n\u0261 h\u011bn \u0261\u01cenx&igrave;n\u0261q&ugrave;<\/div>\n<div>176.\u662f\u7684\uff0c\u6211\u4eec\u5bf9\u65b0\u7cfb\u7edf\u5f88\u611f\u5174\u8da3\u3002<\/div>\n<\/p>\n<p><div>177.Has your company done any research in this field?<\/div>\n<\/p>\n<p><div>q\u01d0n\u0261w&egrave;n \u0261u&igrave;\u0261\u014dn\u0261s\u012b du&igrave;c\u01d0 f&agrave;nch&oacute;u zu&ograve;le r&egrave;nh&eacute; y&aacute;nji\u016b m\u0251<\/div>\n<div>177.\u8bf7\u95ee\u8d35\u516c\u53f8\u5bf9\u6b64\u8303\u7574\u505a\u4e86\u4efb\u4f55\u7814\u7a76\u5417\uff1f<\/div>\n<\/p>\n<p><div>178.Yes, we have done a little. But we have just started and have nothing to show you.<\/div>\n<\/p>\n<p><div>y\u01d2u w\u01d2m&eacute;n zu&ograve;le y&igrave;xi\u0113 d&agrave;nsh&igrave; y\u012bnw&eacute;i w\u01d2m&eacute;n c&aacute;i\u0261\u0101n\u0261 q\u01d0b&ugrave; b&igrave;n\u0261m&eacute;iy\u01d2u r&egrave;nh&eacute; z\u012bli&agrave;o k\u011by\u01d0t&iacute;\u0261\u014dn\u0261 \u0261\u011bi n\u01d0m&eacute;n<\/div>\n<div>178.\u6709\uff0c\u6211\u4eec\u505a\u4e86\u4e00\u4e9b\uff0c\u4f46\u662f\u56e0\u4e3a\u6211\u4eec\u624d\u521a\u8d77\u6b65\uff0c\u5e76\u6ca1\u6709\u4efb\u4f55\u8d44\u6599\u53ef\u4ee5\u63d0\u4f9b\u7ed9\u4f60\u4eec\u3002<\/div>\n<\/p>\n<p><div>179.If you are interested, I will prepare a list of them.<\/div>\n<\/p>\n<p><div>ruguo n&iacute;n \u0261\u01cenx&igrave;n\u0261q&ugrave; de hu&agrave; w\u01d2 k\u011by\u01d0 li&egrave;bi\u01ceo r&agrave;n\u0261 n\u01d0 c\u0101nk\u01ceo<\/div>\n<div>179.\u5982\u679c\u60a8\u611f\u5174\u8da3\u7684\u8bdd\uff0c\u6211\u53ef\u4ee5\u5217\u8868\u8ba9\u4f60\u53c2\u8003\u3002<\/div>\n<\/p>\n<p><div>180.By the way, before leaving this subject, I would like to add a few comments.<\/div>\n<\/p>\n<p><div>z&agrave;i ji&eacute;sh&ugrave; zh&egrave;\u0261e w&egrave;nt&iacute; zh\u012bqi&aacute;n sh&ugrave;nbi&agrave;n y&igrave;t&iacute; w\u01d2 x\u012bw&agrave;n\u0261 n&eacute;n\u0261 z&agrave;i t&iacute;ch\u016b y&igrave;xi\u0113 k&agrave;nf\u01ce<\/div>\n<div>180.\u5728\u7ed3\u675f\u8fd9\u4e2a\u95ee\u9898\u4e4b\u524d\u987a\u4fbf\u4e00\u63d0\uff0c\u6211\u5e0c\u671b\u80fd\u518d\u63d0\u51fa\u4e00\u4e9b\u770b\u6cd5\u3002<\/div><\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-4201428556\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>171.Then the damage must be caused at somewhere along the line where the goods weren&#39;t handled properly.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2874,2853],"tags":[42],"class_list":["post-14947","post","type-post","status-publish","format-standard","hentry","category-speaking","category-spoken-chinese","tag-business-chinese"],"views":179,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/14947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/comments?post=14947"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/14947\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/media?parent=14947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/categories?post=14947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/tags?post=14947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}