{"id":15262,"date":"2019-12-07T17:31:31","date_gmt":"2019-12-07T17:31:31","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-words-phrases\/chinese-idioms-zhi-lu-wei-ma-zhilu-weima-2\/"},"modified":"2019-12-07T17:31:31","modified_gmt":"2019-12-07T17:31:31","slug":"chinese-idioms-zhi-lu-wei-ma-zhilu-weima-2","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/my\/chinese-idioms-zhi-lu-wei-ma-zhilu-weima-2\/","title":{"rendered":"Chinese idioms\uff1a\u6307\u9e7f\u4e3a\u9a6c (Zh\u01d0l\u00f9-w\u00e9im\u01ce)"},"content":{"rendered":"<p style=\"text-align: center; \">\n<p><div>Q&iacute;n Sh\u01d0hu&aacute;ng s\u01d0 le zh\u012b h&ograve;u, t\u0101 de &eacute;rz\u01d0 H&uacute; H&agrave;i d\u0101ng le hu&aacute;ngd&igrave;, y\u011b ji&ugrave; sh&igrave; Q&iacute;n &egrave;r sh&igrave; \uff08g\u014dngyu&aacute;n qi&aacute;n 230 ni&aacute;n \uff5eg\u014dng yu&aacute;n qi&aacute;n 207 ni&aacute;n \uff09. D&agrave;nsh&igrave; d\u0101ngsh&iacute; zh\u01cengw&ograve; ch&aacute;ot&iacute;ng d&agrave;qu&aacute;n de sh&igrave; ch&eacute;ngxi&agrave;ng Zh&agrave;o G\u0101o. T\u0101 xi\u01ceng z&igrave;j\u01d0 d\u0101ng hu&aacute;ngd&igrave;, k\u011b y&ograve;u p&agrave; y\u01d2u r&eacute;n b&ugrave; f&uacute;. Y&uacute;sh&igrave;, t\u0101 xi\u01ceng le y&iacute; g&egrave; b&agrave;nf\u01ce. T\u0101 d\u0101ng zhe h\u011bn du\u014d d&agrave;ch&eacute;n de mi&agrave;n b\u01ce y&igrave; zh\u012b l&ugrave; xi&agrave;n g\u011bi Q&iacute;n &egrave;r sh&igrave;, qu&egrave; shu\u014d:&rdquo;zh&egrave; sh&igrave; y&igrave; p\u01d0 h\u01ceo m\u01ce.&rdquo; Q&iacute;n &egrave;r sh&igrave; t\u012bng le, h\u011bn b&ugrave; m&iacute;ngb&aacute;i, w&egrave;n t\u0101:&rdquo;zh&egrave; m&iacute;ng m&iacute;ng sh&igrave; y&igrave; zh\u012b l&ugrave;, n\u01d0 z\u011bnme shu\u014d sh&igrave; m\u01ce ne?&rdquo; Zh&agrave;o G\u0101o bi&agrave;n w&egrave;n q&iacute;t\u0101 de d&agrave;ch&eacute;n sh&igrave; l&ugrave; h&aacute;i sh&igrave; m\u01ce. Y\u01d2u de d&agrave;ch&eacute;n p&agrave; d&eacute;zu&igrave; ch&eacute;ngxi&agrave;ng, k\u011b y&ograve;u b&uacute; xi\u01ceng q\u012bpi&agrave;n hu&aacute;ngd&igrave;, ji&ugrave; zh&agrave;n z&agrave;i y\u012b p&aacute;ng b&uacute; shu\u014dhu&agrave;; Y\u01d2u de d&agrave;ch&eacute;n sh&ugrave;n zhe Zh&agrave;o G\u0101o de y&igrave;s\u012b, shu\u014d &ldquo;zh&egrave; ji&ugrave; sh&igrave; m\u01ce &ldquo;; h&aacute;i y\u01d2u y&igrave; xi\u0113 zh&egrave;ngzh&iacute; ch&eacute;ngsh&iacute; de d&agrave;ch&eacute;n shu\u014d &ldquo;zh&egrave; sh&igrave; l&ugrave;, b&uacute; sh&igrave; m\u01ce.&rdquo; Y&uacute;sh&igrave;, Zh&agrave;o G\u0101o zh\u012bd&agrave;o le shu&iacute; g\u01cen f\u01cendu&igrave; t\u0101, h&ograve;ul&aacute;i ji&ugrave; zh\u01ceo j\u012bhu&igrave; b\u01ce shu\u014d sh&iacute;hu&agrave; de r&eacute;n d\u014du sh\u0101 le.<br \/>  \t\u79e6\u59cb\u7687\u6b7b\u4e86\u4e4b\u540e\uff0c\u4ed6\u7684\u513f\u5b50\u80e1\u4ea5\u5f53\u4e86\u7687\u5e1d\uff0c\u4e5f\u5c31\u662f\u79e6\u4e8c\u4e16\uff08\u516c\u5143\u524d230\u5e74\uff5e\u516c\u5143\u524d207\u5e74\uff09\u3002\u4f46\u662f\u5f53\u65f6\u638c\u63e1\u671d\u5ef7\u5927\u6743\u7684\u662f\u4e1e\u76f8\u8d75\u9ad8\u3002\u4ed6\u60f3\u81ea\u5df1\u5f53\u7687\u5e1d\uff0c\u53ef\u53c8\u6015\u6709\u4eba\u4e0d\u670d\u3002\u4e8e\u662f\uff0c\u4ed6\u60f3\u4e86\u4e00\u4e2a\u529e\u6cd5\u3002\u4ed6\u5f53\u7740\u5f88\u591a\u5927\u81e3\u7684\u9762\u628a\u4e00\u53ea\u9e7f\u732e\u7ed9\u79e6\u4e8c\u4e16\uff0c\u5374\u8bf4\uff1a&ldquo;\u8fd9\u662f\u4e00\u5339\u597d\u9a6c\u3002&rdquo;\u79e6\u4e8c\u4e16\u542c\u4e86\uff0c\u5f88\u4e0d\u660e\u767d\uff0c\u95ee\u4ed6\uff1a&ldquo;\u8fd9\u660e\u660e\u662f\u4e00\u53ea\u9e7f\uff0c\u4f60\u600e\u4e48\u8bf4\u662f\u9a6c\u5462\uff1f&rdquo;\u8d75\u9ad8\u4fbf\u95ee\u5176\u5b83\u7684\u5927\u81e3\u662f\u9e7f\u8fd8\u662f\u9a6c\u3002\u6709\u7684\u5927\u81e3\u6015\u5f97\u7f6a\u4e1e\u76f8\uff0c\u53ef\u53c8\u4e0d\u60f3\u6b3a\u9a97\u7687\u5e1d\uff0c\u5c31\u7ad9\u5728\u4e00\u65c1\u4e0d\u8bf4\u8bdd\uff1b\u6709\u7684\u5927\u81e3\u987a\u7740\u8d75\u9ad8\u7684\u610f\u601d\uff0c\u8bf4&ldquo;\u8fd9\u5c31\u662f\u9a6c&rdquo;\uff1b\u8fd8\u6709\u4e00\u4e9b\u6b63\u76f4\u8bda\u5b9e\u7684\u5927\u81e3\u8bf4&ldquo;\u8fd9\u662f\u9e7f\uff0c\u4e0d\u662f\u9a6c\u3002&rdquo;\u4e8e\u662f\uff0c\u8d75\u9ad8\u77e5\u9053\u4e86\u8c01\u6562\u53cd\u5bf9\u4ed6\uff0c\u540e\u6765\u5c31\u627e\u673a\u4f1a\u628a\u8bf4\u5b9e\u8bdd\u7684\u4eba\u90fd\u6740\u4e86\u3002<\/div>\n<p>  \t<\/p>\n<div>After the death of Emperor Qin Shi Huang (the first emperor of the Qin Dynasty), his son Hu Hai succeeded him and became emperor, called Qin Er Shi, which literally means the second emperor of the Qin Dynasty (his reign was from 230 to 207 B.C). However, the man who grasped the real power was the Prime Minister Zhao Gao at that time. Zhao wanted to be the emperor himself, but he was afraid that he wouldn&#39;t be admitted by someone. Hence, an idea just came into his mind. He offered a deer to Qin Er Shi in the presence of many ministers, and said &quot;This is a wonderful horse.&quot; Qin was puzzled at his words and asked, &quot;This is obviously a deer, but why do you call it a horse?&quot; Zhao then asked the other ministers whether it was a deer or a horse. Some ministers said nothing because they did not dare to offend the Prime Minister and they were also unwilling to cheat the Emperor. As for the others, some of them said &quot;This is a horse&quot; for the support of Zhao Gao, but the rest upright and honest ministers stood out and said, &quot;This is a deer not a horse&quot;, which helped Zhao Gao finally realized who were on his side and who were not. Later he found excuses and had those who were against him killed.<\/div>\n<p>  \t<strong>Words\uff1a<\/strong><br \/>  \t\u671d\u5ef7ch&aacute;ot&iacute;ng\uff1a imperial court (n.)<br \/>  \t\u4e1e\u76f8ch&eacute;ngxi&agrave;ng\uff1a prime minister (n.)<br \/>  \t\u5927\u81e3d&agrave;ch&eacute;n\uff1a minister (of a monarchy) ( n. )<br \/>  \t\u9e7fl&ugrave;: deer (n.)<br \/>  \t\u660e\u660em&iacute;ngm&iacute;ng\uff1a obviously (adv. )<br \/>  \t\u5f97\u7f6ad&eacute;zu&igrave;\uff1a offend (v.)<br \/>  \t\u673a\u4f1aj\u012b hu&igrave;\uff1a opportunity (n.)<\/p>\n<p>  \t<strong>Meaning\uff1a<\/strong>  \t<\/p>\n<div>\u6307\u9e7f\u4e3a\u9a6c\uff1a\u6307\u7740\u9e7f\uff0c\u8bf4\u662f\u9a6c\u3002\u6bd4\u55bb\u6545\u610f\u98a0\u5012\u9ed1\u767d\uff0c\u6df7\u6dc6\u662f\u975e\u3002<\/div>\n<div>Meaning: Point to a deer, and call it a horse, which is used to describe someone deliberately distorting the truth.<\/div>\n<p>  \t<strong>Sentences\uff1a<\/strong>  \t<\/p>\n<div>1.Xi\u01ceo Li&uacute; w&egrave;i le y\u01censh&igrave; z&igrave;j\u01d0 de gu&ograve;cu&ograve;, z&agrave;i j\u012bngl\u01d0 mi&agrave;nqi&aacute;n zh\u01d0l&ugrave;-w&eacute;im\u01ce, y\u01d0n q\u01d0 le t&oacute;ngsh&igrave; men de b&ugrave;m\u01cen.<br \/>  \t\u5c0f\u5218\u4e3a\u4e86\u63a9\u9970\u81ea\u5df1\u7684\u8fc7\u9519\uff0c\u5728\u7ecf\u7406\u9762\u524d\u6307\u9e7f\u4e3a\u9a6c\uff0c\u5f15\u8d77\u4e86\u540c\u4e8b\u4eec\u7684\u4e0d\u6ee1\u3002<\/div>\n<div>In order to cover his mistake, Xiao Liu zhilu-weima before the manager, which aroused the dissatisfaction among his colleagues.<\/div>\n<p>  \t<\/p>\n<div>2. Z&agrave;i f\u01cet&iacute;ng sh&agrave;ng, w&egrave;i le b\u0101ng z&igrave;j\u01d0 zh&agrave;ngf\u016b tu\u014dzu&igrave;, Zh\u0101ng xi\u01ceoji\u011b zh\u01d0l&ugrave;-w&eacute;im\u01ce, b\u01ce z&eacute;r&egrave;n d\u014du tu\u012b d&agrave;o sh&ograve;uh&agrave;i zh\u011b sh\u0113n sh&agrave;ng.<br \/>  \t\u5728\u6cd5\u5ead\u4e0a\uff0c\u4e3a\u4e86\u5e2e\u81ea\u5df1\u4e08\u592b\u8131\u7f6a\uff0c\u5f20\u5c0f\u59d0\u6307\u9e7f\u4e3a\u9a6c\uff0c\u628a\u8d23\u4efb\u90fd\u63a8\u5230\u53d7\u5bb3\u8005\u8eab\u4e0a\u3002<\/div>\n<div>In order to exculpate her husband from the guilt, Miss Zhang zhilu-weima at the court and shifted off all the responsibilities to the victim.<\/div>\n<\/p>\n<p>  \t\u539f\u6587\u94fe\u63a5  \t<\/p>\n<p>  \t\u58f0\u660e\uff1a\u6caa\u6c5f\u7f51\u9ad8\u5ea6\u91cd\u89c6\u77e5\u8bc6\u4ea7\u6743\u4fdd\u62a4\uff0c\u53d1\u73b0\u672c\u7f51\u7ad9\u53d1\u5e03\u7684\u4fe1\u606f\u5305\u542b\u6709\u4fb5\u72af\u5176\u8457\u4f5c\u6743\u7684\u94fe\u63a5\u5185\u5bb9\u65f6\uff0c\u8bf7\u8054\u7cfb\u6211\u4eec\uff0c\u6211\u4eec\u5c06\u505a\u76f8\u5e94\u5904\u7406\u3002<\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-811711980\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Q&iacute;n Sh\u01d0hu&aacute;ng s\u01d0 le zh\u012b h&ograve;u, t\u0101 de &eacute;rz\u01d0 H&uacute; H&agrave;i d\u0101ng le hu&aacute;ngd&igrave;, y\u011b ji&ugrave; sh&igrave; Q&iacute;n &egrave;r sh&igrave; \uff08g\u014dngyu&aacute;n qi&aacute;n 230 ni&aacute;n \uff5eg\u014dng yu&aacute;n qi&aacute;n 207 ni&aacute;n \uff09. D&agrave;nsh&igrave; d\u0101ngsh&iacute; zh\u01cengw&ograve; ch&aacute;ot&iacute;ng d&agrave;qu&aacute;n de sh&igrave; ch&eacute;ngxi&agrave;ng Zh&agrave;o G\u0101o. T\u0101 xi\u01ceng z&igrave;j\u01d0 d\u0101ng hu&aacute;ngd&igrave;, k\u011b y&ograve;u p&agrave; y\u01d2u r&eacute;n b&ugrave; f&uacute;. Y&uacute;sh&igrave;, t\u0101 xi\u01ceng le y&iacute; g&egrave; b&agrave;nf\u01ce. T\u0101 d\u0101ng zhe h\u011bn du\u014d d&agrave;ch&eacute;n de mi&agrave;n b\u01ce y&igrave; zh\u012b l&ugrave; xi&agrave;n g\u011bi Q&iacute;n &egrave;r sh&igrave;, qu&egrave; shu\u014d:&rdquo;zh&egrave; sh&igrave; y&igrave; p\u01d0 h\u01ceo m\u01ce.&rdquo; Q&iacute;n &egrave;r sh&igrave; t\u012bng le, h\u011bn b&ugrave; m&iacute;ngb&aacute;i, w&egrave;n t\u0101:&rdquo;zh&egrave; m&iacute;ng m&iacute;ng sh&igrave; y&igrave; zh\u012b l&ugrave;, n\u01d0 z\u011bnme shu\u014d sh&igrave; m\u01ce ne?&rdquo; Zh&agrave;o G\u0101o bi&agrave;n w&egrave;n q&iacute;t\u0101 de d&agrave;ch&eacute;n sh&igrave; l&ugrave; h&aacute;i sh&igrave; m\u01ce. Y\u01d2u de d&agrave;ch&eacute;n p&agrave; d&eacute;zu&igrave; ch&eacute;ngxi&agrave;ng, k\u011b y&ograve;u b&uacute; xi\u01ceng q\u012bpi&agrave;n hu&aacute;ngd&igrave;, ji&ugrave; zh&agrave;n z&agrave;i y\u012b p&aacute;ng b&uacute; shu\u014dhu&agrave;; Y\u01d2u de d&agrave;ch&eacute;n sh&ugrave;n zhe Zh&agrave;o G\u0101o de y&igrave;s\u012b, shu\u014d &ldquo;zh&egrave; ji&ugrave; sh&igrave; m\u01ce &ldquo;; h&aacute;i y\u01d2u y&igrave; xi\u0113 zh&egrave;ngzh&iacute; ch&eacute;ngsh&iacute; de d&agrave;ch&eacute;n shu\u014d &ldquo;zh&egrave; sh&igrave; l&ugrave;, b&uacute; sh&igrave; m\u01ce.&rdquo; Y&uacute;sh&igrave;, Zh&agrave;o G\u0101o zh\u012bd&agrave;o le shu&iacute; g\u01cen f\u01cendu&igrave; t\u0101, h&ograve;ul&aacute;i ji&ugrave; zh\u01ceo j\u012bhu&igrave; b\u01ce shu\u014d sh&iacute;hu&agrave; de r&eacute;n d\u014du sh\u0101 le.<br \/>\n  \t\u79e6\u59cb\u7687\u6b7b\u4e86\u4e4b\u540e\uff0c\u4ed6\u7684\u513f\u5b50\u80e1\u4ea5\u5f53\u4e86\u7687\u5e1d\uff0c\u4e5f\u5c31\u662f\u79e6\u4e8c\u4e16\uff08\u516c\u5143\u524d230\u5e74\uff5e\u516c\u5143\u524d207\u5e74\uff09\u3002\u4f46\u662f\u5f53\u65f6\u638c\u63e1\u671d\u5ef7\u5927\u6743\u7684\u662f\u4e1e\u76f8\u8d75\u9ad8\u3002\u4ed6\u60f3\u81ea\u5df1\u5f53\u7687\u5e1d\uff0c\u53ef\u53c8\u6015\u6709\u4eba\u4e0d\u670d\u3002\u4e8e\u662f\uff0c\u4ed6\u60f3\u4e86\u4e00\u4e2a\u529e\u6cd5\u3002\u4ed6\u5f53\u7740\u5f88\u591a\u5927\u81e3\u7684\u9762\u628a\u4e00\u53ea\u9e7f\u732e\u7ed9\u79e6\u4e8c\u4e16\uff0c\u5374\u8bf4\uff1a&ldquo;\u8fd9\u662f\u4e00\u5339\u597d\u9a6c\u3002&rdquo;\u79e6\u4e8c\u4e16\u542c\u4e86\uff0c\u5f88\u4e0d\u660e\u767d\uff0c\u95ee\u4ed6\uff1a&ldquo;\u8fd9\u660e\u660e\u662f\u4e00\u53ea\u9e7f\uff0c\u4f60\u600e\u4e48\u8bf4\u662f\u9a6c\u5462\uff1f&rdquo;\u8d75\u9ad8\u4fbf\u95ee\u5176\u5b83\u7684\u5927\u81e3\u662f\u9e7f\u8fd8\u662f\u9a6c\u3002\u6709\u7684\u5927\u81e3\u6015\u5f97\u7f6a\u4e1e\u76f8\uff0c\u53ef\u53c8\u4e0d\u60f3\u6b3a\u9a97\u7687\u5e1d\uff0c\u5c31\u7ad9\u5728\u4e00\u65c1\u4e0d\u8bf4\u8bdd\uff1b\u6709\u7684\u5927\u81e3\u987a\u7740\u8d75\u9ad8\u7684\u610f\u601d\uff0c\u8bf4&ldquo;\u8fd9\u5c31\u662f\u9a6c&rdquo;\uff1b\u8fd8\u6709\u4e00\u4e9b\u6b63\u76f4\u8bda\u5b9e\u7684\u5927\u81e3\u8bf4&ldquo;\u8fd9\u662f\u9e7f\uff0c\u4e0d\u662f\u9a6c\u3002&rdquo;\u4e8e\u662f\uff0c\u8d75\u9ad8\u77e5\u9053\u4e86\u8c01\u6562\u53cd\u5bf9\u4ed6\uff0c\u540e\u6765\u5c31\u627e\u673a\u4f1a\u628a\u8bf4\u5b9e\u8bdd\u7684\u4eba\u90fd\u6740\u4e86\u3002<br \/>\n  \tAfter the death of Emperor Qin Shi Huang (the first emperor of the Qin Dynasty), his son Hu Hai succeeded him and became emperor, called Qin Er Shi, which literally means the second emperor of the Qin Dynasty (his reign was from 230 to 207 B.C). However, the man who grasped the real power was the Prime Minister Zhao Gao at that time. Zhao wanted to be the emperor himself, but he was afraid that he wouldn&#39;t be admitted by someone. Hence, an idea just came into his mind. He offered a deer to Qin Er Shi in the presence of many ministers, and said &quot;This is a wonderful horse.&quot; Qin was puzzled at his words and asked, &quot;This is obviously a deer, but why do you call it a horse?&quot; Zhao then asked the other ministers whether it was a deer or a horse. Some ministers said nothing because they did not dare to offend the Prime Minister and they were also unwilling to cheat the Emperor. As for the others, some of them said &quot;This is a horse&quot; for the support of Zhao Gao, but the rest upright and honest ministers stood out and said, &quot;This is a deer not a horse&quot;, which helped Zhao Gao finally realized who were on his side and who were not. Later he found excuses and had those who were against him killed.<br \/>\n  \tWords\uff1a<br \/>\n  \t\u671d\u5ef7ch&aacute;ot&iacute;ng\uff1a imperial court (n.)<br \/>\n  \t\u4e1e\u76f8ch&eacute;ngxi&agrave;ng\uff1a prime minister (n.)<br \/>\n  \t\u5927\u81e3d&agrave;ch&eacute;n\uff1a minister (of a monarchy) ( n. )<br \/>\n  \t\u9e7fl&ugrave;: deer (n.)<br \/>\n  \t\u660e\u660em&iacute;ngm&iacute;ng\uff1a obviously (adv. )<br \/>\n  \t\u5f97\u7f6ad&eacute;zu&igrave;\uff1a offend (v.)<br \/>\n  \t\u673a\u4f1aj\u012b hu&igrave;\uff1a opportunity (n.)<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,2843],"tags":[54],"class_list":["post-15262","post","type-post","status-publish","format-standard","hentry","category-chinese-words-phrases","category-news-vocabulary","tag-chinese-idiom"],"views":224,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/15262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/comments?post=15262"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/15262\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/media?parent=15262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/categories?post=15262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/tags?post=15262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}