{"id":15313,"date":"2019-12-09T20:47:44","date_gmt":"2019-12-09T20:47:44","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-words-phrases\/chinese-idioms-shuang-guan-qi-xia-shuang-guan-qi-xia-2\/"},"modified":"2019-12-09T20:47:44","modified_gmt":"2019-12-09T20:47:44","slug":"chinese-idioms-shuang-guan-qi-xia-shuang-guan-qi-xia-2","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/my\/chinese-idioms-shuang-guan-qi-xia-shuang-guan-qi-xia-2\/","title":{"rendered":"Chinese idioms:\u53cc\u7ba1\u9f50\u4e0b Shu\u0101ng gu\u0101n q\u00ed xi\u00e0"},"content":{"rendered":"<\/p>\n<p><div>T&aacute;n\u0261ch&aacute;o y\u01d2u y&iacute;w&egrave;i zh&ugrave;m&iacute;n\u0261de hu&agrave;ji\u0101 ji&agrave;o Zh\u0101n\u0261z&agrave;o. T\u0101 sh&agrave;nch&aacute;n\u0261 hu&agrave; sh\u0101nshu\u01d0, s\u014dn\u0261sh&iacute;. Zh\u0101n\u0261z&agrave;o zu&ograve;hu&agrave;de sh&iacute;hou, zu\u01d2y&ograve;ush\u01d2u \u0261&egrave;w&ograve; y&igrave;zh\u012bb\u01d0, k&eacute;y\u01d0 t&oacute;n\u0261sh&iacute; z&agrave;i zh\u01d0sh&agrave;n\u0261 zu&ograve;hu&agrave;. Y&igrave;zh\u012bb\u01d0 hu&agrave; c\u0101n\u0261cu&igrave;de s\u014dn\u0261zh\u012b, l&igrave;n\u0261y&igrave;zh\u012bb\u01d0 hu&agrave; k\u016b\u0261\u0101nqi&uacute;zh\u012b, hu&agrave;ch\u016bde s\u014dn\u0261sh&ugrave; w&eacute;imi&agrave;ow&eacute;ixi\u0101o, r&eacute;nmen d\u014dushu\u014d t\u0101sh&igrave; sh&eacute;nb\u01d0.<br \/>  \t\u5510\u671d\u6709\u4e00\u4f4d\u8457\u540d\u7684\u753b\u5bb6\u53eb\u5f20\u71e5\uff0c\u4ed6\u64c5\u957f\u753b\u5c71\u6c34\u3001\u677e\u77f3\u3002\u5f20\u71e5\u4f5c\u753b\u7684\u65f6\u5019\uff0c\u5de6\u53f3\u624b\u5404\u63e1\u4e00\u652f\u7b14\uff0c\u53ef\u4ee5\u540c\u65f6\u5728\u7eb8\u4e0a\u4f5c\u753b\u3002\u4e00\u652f\u7b14\u753b\u82cd\u7fe0\u7684\u677e\u679d\uff0c\u53e6\u4e00\u652f\u7b14\u753b\u67af\u5e72\u866c\u679d\uff0c\u753b\u51fa\u7684\u677e\u6811\u60df\u5999\u60df\u8096\uff0c\u4eba\u4eec\u90fd\u8bf4\u4ed6\u662f\u795e\u7b14\u3002  \t<\/div>\n<div>During the Tang Dynasty, there lived a famous artist named Zhang Zao who was a master painter of landscapes, pine trees and stones. He could paint with a brush in each hand, one brush portraying dark green pine branches while the other illustrated dried up branches. His paintings were very vivid and many praised him for possessing a magic pen.  \t<\/div>\n<\/p>\n<p>  \t<strong>Words<\/strong><br \/>  \t\u677e\u77f3<script language=\"Javascript\">GetWord(\"\u677e\u77f3\");<\/script>:(s\u014dngsh&iacute;)n. Pine and Stone (An important element of Chinese landscape painting featuring pine trees and stones)<br \/>  \t\u82cd\u7fe0<script language=\"Javascript\">GetWord(\"\u82cd\u7fe0\");<\/script>:(c\u0101ngcu&igrave;) adj. dark green<br \/>  \t\u866c\u679d<script language=\"Javascript\">GetWord(\"\u866c\u679d\");<\/script>\ud83d\ude41 qi&uacute; zh\u012b) n. the curled branch of a tree<\/p>\n<p>  \t<strong>Meanings<br \/>  \t<\/strong><\/p>\n<div>&ldquo;Shu\u0101n\u0261 \u0261u\u01cen q&iacute; xi&agrave;&rdquo;, &ldquo;\u0261u\u01cen&rdquo; zh\u01d0 b\u01d0, yu&aacute;nzh\u01d0 sh\u01d2uw&ograve; shu\u0101n\u0261b\u01d0 t&oacute;n\u0261sh&iacute; zu&ograve;hu&agrave;. H&ograve;u b\u01d0y&ugrave; zu&ograve; y&iacute;ji&agrave;nsh&igrave; li\u01cen\u0261\u0261&egrave; f\u0101n\u0261mi&agrave;n t&oacute;n\u0261sh&iacute; j&igrave;nx&iacute;n\u0261 hu&ograve; li\u01cen\u0261zh\u01d2n\u0261 f\u0101n\u0261f\u01ce t&oacute;n\u0261sh&iacute; sh\u01d0y&ograve;n\u0261.<br \/>  \t&ldquo;\u53cc\u7ba1\u9f50\u4e0b&rdquo;\uff0c&ldquo;\u7ba1&rdquo;\u6307\u7b14\uff0c\u539f\u6307\u624b\u63e1\u53cc\u7b14\u540c\u65f6\u4f5c\u753b\u3002\u540e\u6bd4\u55bb\u505a\u4e00\u4ef6\u4e8b\u4e24\u4e2a\u65b9\u9762\u540c\u65f6\u8fdb\u884c\u6216\u4e24\u79cd\u65b9\u6cd5\u540c\u65f6\u4f7f\u7528\u3002  \t<\/div>\n<div>&quot;\u53cc\u7ba1\u9f50\u4e0b&rdquo;\uff0c&ldquo;\u7ba1&rdquo; refers to a brush. Its original meaning was to paint with two brushes, one in each hand. Now its used as a metaphor for a two-pronged approach.  \t<\/div>\n<\/p>\n<p>  \t<strong>Sentences<br \/>  \t<\/strong><\/p>\n<div>1\u3001T\u0101men c\u01ceiy&ograve;n\u0261 ji&agrave;n\u0261ji&agrave; h&eacute; s&ograve;n\u0261hu&ograve; sh&agrave;n\u0261m&eacute;n li\u01cen\u0261zh\u01d2n\u0261 xi\u0101osh&ograve;u sh\u01d2udu&agrave;n, shu\u0101n\u0261\u0261u\u01cenq&iacute;xi&agrave;, zh&egrave;\u0261eyu&egrave; de y&iacute;n\u0261y&egrave;&eacute; \u0261u\u01d2r&aacute;n sh&agrave;n\u0261sh\u0113ngle b&ugrave;sh\u01ceo.<br \/>  \t\u4ed6\u4eec\u91c7\u7528\u964d\u4ef7\u548c\u9001\u8d27\u4e0a\u95e8\u4e24\u79cd\u9500\u552e\u624b\u6bb5\uff0c\u53cc\u7ba1\u9f50\u4e0b\uff0c\u8fd9\u4e2a\u6708\u7684\u8425\u4e1a\u989d\u679c\u7136\u4e0a\u5347\u4e86\u4e0d\u5c11\u3002  \t<\/div>\n<div>They used two methods to reduce prices and deliver goods door to door, which led to a marked increase in the volume of sales this month.<\/div>\n<\/p>\n<p><div>2\u3001Zh&igrave;li&aacute;o zh&egrave;zh\u01d2n\u0261b&igrave;n\u0261 ji&ugrave;y&agrave;o c&aacute;iq\u01d4 &agrave;nm&oacute; h&eacute; ch\u012by&agrave;o shu\u0101n\u0261\u0261u\u01cenq&iacute;xi&agrave; de f\u0101n\u0261sh&igrave;.<br \/>  \t\u6cbb\u7597\u8fd9\u79cd\u75c5\u5c31\u8981\u91c7\u53d6\u6309\u6469\u548c\u5403\u836f\u53cc\u7ba1\u9f50\u4e0b\u7684\u65b9\u5f0f\u3002  \t<\/div>\n<div>Both massage and medicine are required to treat this illness.<\/div>\n<p>  \t\u539f\u6587\u94fe\u63a5<\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-2963642721\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>T&aacute;n\u0261ch&aacute;o y\u01d2u y&iacute;w&egrave;i zh&ugrave;m&iacute;n\u0261de hu&agrave;ji\u0101 ji&agrave;o Zh\u0101n\u0261z&agrave;o. T\u0101 sh&agrave;nch&aacute;n\u0261 hu&agrave; sh\u0101nshu\u01d0, s\u014dn\u0261sh&iacute;. Zh\u0101n\u0261z&agrave;o zu&ograve;hu&agrave;de sh&iacute;hou, zu\u01d2y&ograve;ush\u01d2u \u0261&egrave;w&ograve; y&igrave;zh\u012bb\u01d0, k&eacute;y\u01d0 t&oacute;n\u0261sh&iacute; z&agrave;i zh\u01d0sh&agrave;n\u0261 zu&ograve;hu&agrave;. Y&igrave;zh\u012bb\u01d0 hu&agrave; c\u0101n\u0261cu&igrave;de s\u014dn\u0261zh\u012b, l&igrave;n\u0261y&igrave;zh\u012bb\u01d0 hu&agrave; k\u016b\u0261\u0101nqi&uacute;zh\u012b, hu&agrave;ch\u016bde s\u014dn\u0261sh&ugrave; w&eacute;imi&agrave;ow&eacute;ixi\u0101o, r&eacute;nmen d\u014dushu\u014d t\u0101sh&igrave; sh&eacute;nb\u01d0.<br \/>\n  \t\u5510\u671d\u6709\u4e00\u4f4d\u8457\u540d\u7684\u753b\u5bb6\u53eb\u5f20\u71e5\uff0c\u4ed6\u64c5\u957f\u753b\u5c71\u6c34\u3001\u677e\u77f3\u3002\u5f20\u71e5\u4f5c\u753b\u7684\u65f6\u5019\uff0c\u5de6\u53f3\u624b\u5404\u63e1\u4e00\u652f\u7b14\uff0c\u53ef\u4ee5\u540c\u65f6\u5728\u7eb8\u4e0a\u4f5c\u753b\u3002\u4e00\u652f\u7b14\u753b\u82cd\u7fe0\u7684\u677e\u679d\uff0c\u53e6\u4e00\u652f\u7b14\u753b\u67af\u5e72\u866c\u679d\uff0c\u753b\u51fa\u7684\u677e\u6811\u60df\u5999\u60df\u8096\uff0c\u4eba\u4eec\u90fd\u8bf4\u4ed6\u662f\u795e\u7b14\u3002<br \/>\n  \tDuring the Tang Dynasty, there lived a famous artist named Zhang Zao who was a master painter of landscapes, pine trees and stones. He could paint with a brush in each hand, one brush portraying dark green pine branches while the other illustrated dried up branches. His paintings were very vivid and many praised him for possessing a magic pen.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,2843],"tags":[54],"class_list":["post-15313","post","type-post","status-publish","format-standard","hentry","category-chinese-words-phrases","category-news-vocabulary","tag-chinese-idiom"],"views":241,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/15313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/comments?post=15313"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/15313\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/media?parent=15313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/categories?post=15313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/tags?post=15313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}