{"id":7320,"date":"2019-11-04T04:27:57","date_gmt":"2019-11-04T04:27:57","guid":{"rendered":"http:\/\/chinesemoment.com\/chinese-words-phrases\/chinese-language-vocabulary-han-yu-ci-hui-to-judge-people-by-appearancechinese\/"},"modified":"2019-11-04T04:27:57","modified_gmt":"2019-11-04T04:27:57","slug":"chinese-language-vocabulary-han-yu-ci-hui-to-judge-people-by-appearancechinese","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/my\/chinese-language-vocabulary-han-yu-ci-hui-to-judge-people-by-appearancechinese\/","title":{"rendered":"Chinese language vocabulary \u6c49\u8bed\u8bcd\u6c47 to judge people by appearance\uff08Chinese)"},"content":{"rendered":"<div><strong>&ldquo;Y\u01d0m&agrave;oq\u01d4r&eacute;n&rdquo; de di\u01cen \u0261&ugrave;<\/strong>  <\/p>\n<p><strong>&rdquo;\u4ee5\u8c8c\u53d6\u4eba&ldquo;\u7684\u5178\u6545 &nbsp; &nbsp;<\/strong><\/p>\n<p>K\u01d2n\u0261z\u01d0\u3000y\u01d2u\u3000x\u01d4x\u01d4\uff0ddu\u014ddu\u014d\u3000d&igrave;z\u01d0\uff0cq&iacute;zh\u014dn\u0261\u3000y\u01d2u\u3000y\u012b\u3000\u0261&egrave;\u3000m&iacute;n\u0261\u3000ji&agrave;o\u3000Z\u01cei-Y\u01d4\u3000de\uff0ch\u011bn\u3000 sh&igrave;\u3000n&eacute;n\u0261shu\u014dhu&igrave;d&agrave;o\u3002T\u0101\u3000k\u0101ish\u01d0\u3000\u0261\u011bi\u3000K\u01d2n\u0261z\u01d0\u3000de\u3000y&igrave;nxi&agrave;n\u0261\u3000b&ugrave;cu&ograve;\uff0cd&agrave;n\u3000h&ograve;ul&aacute;i\u3000 ji&agrave;nji&agrave;n\u3000de\u3000l&ograve;uch\u016b\u3000le\u3000b\u011bnxi&agrave;n\u0261\uff1aj&igrave;\u3000w&uacute;\u3000r&eacute;nd&eacute;\u3000y&ograve;u\u3000sh&iacute;f\u0113n\u3000l\u01cendu&ograve;\uff1bd&agrave;\u3000b&aacute;iti\u0101n\u3000 b&ugrave;\u3000d&uacute;sh\u016b\u3000t\u012bn\u0261ji\u01cen\u0261\uff0ct\u01cen\u0261\u3000z&agrave;i\u3000chu&aacute;n\u0261\u3000sh&agrave;n\u0261\u3000shu&igrave;\u3000d&agrave;ji&agrave;o\u3002W&egrave;ic\u01d0\uff0cK\u01d2n\u0261z\u01d0\u3000m&agrave;\u3000t\u0101\u3000 sh&igrave;\u3000xi\u01d4m&ugrave;b&ugrave;k\u011bdi\u0101o.<br \/>  \u5b54\u5b50\u6709\u8bb8\u8bb8\u591a\u591a\u5f1f\u5b50\uff0c\u5176\u4e2d\u6709\u4e00\u4e2a\u540d\u53eb\u5bb0\u4e88\u7684\uff0c\u5f88\u662f\u80fd\u8bf4\u4f1a\u9053\u3002\u4ed6\u5f00\u59cb\u7ed9\u5b54\u5b50\u7684\u5370\u8c61\u4e0d\u9519\uff0c\u4f46\u540e\u6765\u6e10\u6e10\u5730\u9732\u51fa\u4e86\u672c\u76f8\uff1a\u65e2\u65e0\u4ec1\u5fb7\u53c8\u5341\u5206\u61d2\u60f0\uff1b\u5927\u767d\u5929\u4e0d\u8bfb\u4e66\u542c\u8bb2\uff0c\u8eba\u5728\u5e8a\u4e0a\u7761\u5927\u89c9\u3002\u4e3a\u6b64\uff0c\u5b54\u5b50\u9a82\u4ed6\u662f\u673d\u6728\u4e0d\u53ef\u96d5\u3002<\/p>\n<p>K\u01d2n\u0261z\u01d0\u3000de\u3000l&igrave;n\u0261\u3000y\u012b\u3000\u0261&egrave;\u3000d&igrave;z\u01d0\uff0cji&agrave;o\u3000T&aacute;nt&aacute;i\u3000Mi&egrave;m&iacute;n\u0261\uff0cb\u01d0\u3000K\u01d2n\u0261z\u01d0\u3000xi\u01ceo\u3000  s\u0101nsh&iacute;ji\u01d4\u3000su&igrave;\u3002T&aacute;nt&aacute;i\u3000Mi&egrave;m&iacute;n\u0261&nbsp;de\u3000t\u01d0t&agrave;i\u3000h&eacute;\u3000xi&agrave;n\u0261m&agrave;o\u3000h\u011bn\u3000ch\u01d2ul&ograve;u\uff0cxi\u01cen\u0261\u3000y&agrave;o\u3000 sh&igrave;f&egrave;n\u0261\u3000K\u01d2n\u0261z\u01d0\u3002K\u01d2n\u0261z\u01d0\u3000k\u0101ish\u01d0\u3000r&egrave;nw&eacute;i\u3000t\u0101\u3000z\u012bzh&igrave;\u3000d\u012bxi&agrave;\uff0cb&ugrave;\u3000hu&igrave;\u3000ch&eacute;n\u0261c&aacute;i\u3002D&agrave;n\u3000 t\u0101\u3000c&oacute;n\u0261\u3000sh\u012b\u3000xu&eacute;x&iacute;\u3000h&ograve;u\uff0chu&iacute;q&ugrave;\u3000ji&ugrave;\u3000zh&igrave;\u3000l&igrave;\u3000y&uacute;\u3000xi\u016bsh\u0113n\u3000sh&iacute;ji&agrave;n\uff0cch\u01d4sh&igrave;\u3000 \u0261u\u0101n\u0261m&iacute;n\u0261-zh&egrave;n\u0261d&agrave;\u3002H&ograve;ul&aacute;i\uff0cT&aacute;nt&aacute;i\u3000Mi&egrave;m&iacute;n\u0261\u3000y&oacute;ul&igrave;\u3000d&agrave;o\u3000Ch&aacute;n\u0261Ji\u0101n\u0261\uff0c\u0261\u0113nsu&iacute;\u3000t\u0101\u3000 de\u3000d&igrave;z\u01d0\u3000y\u01d2u\u3000s\u0101nb\u01cei\u3000r&eacute;n\uff0csh\u0113n\u0261y&ugrave;\u3000h\u011bn\u3000\u0261\u0101o\uff0c\u0261&egrave;\u3000\u0261u&oacute;\u3000d\u014du\u3000chu&aacute;ns&ograve;n\u0261\u3000t\u0101\u3000de\u3000 m&iacute;n\u0261zi\u3002<br \/>  \u5b54\u5b50\u7684\u53e6\u4e00\u4e2a\u5f1f\u5b50\uff0c\u53eb\u6fb9\u53f0\u706d\u660e\uff0c\u6bd4\u5b54\u5b50\u5c0f\u4e09\u5341\u4e5d\u5c81\u3002\u5b50\u7fbd\u7684\u4f53\u6001\u548c\u76f8\u8c8c\u5f88\u4e11\u964b\uff0c\u60f3\u8981\u4e8b\u5949\u5b54\u5b50\u3002\u5b54\u5b50\u5f00\u59cb\u8ba4\u4e3a\u4ed6\u8d44\u8d28\u4f4e\u4e0b\uff0c\u4e0d\u4f1a\u6210\u624d\u3002\u4f46\u4ed6\u4ece\u5e08\u5b66\u4e60\u540e\uff0c\u56de\u53bb\u5c31\u81f4\u529b\u4e8e\u4fee\u8eab\u5b9e\u8df5\uff0c\u5904\u4e8b\u5149\u660e\u6b63\u5927\u3002\u540e\u6765\uff0c\u6fb9\u53f0\u706d\u660e\u6e38\u5386\u5230\u957f\u6c5f\uff0c\u8ddf\u968f\u4ed6\u7684\u5f1f\u5b50\u6709\u4e09\u767e\u4eba\uff0c\u58f0\u8a89\u5f88\u9ad8\uff0c\u5404\u56fd\u90fd\u4f20\u8bf5\u4ed6\u7684\u540d\u5b57\u3002<\/p>\n<p>K\u01d2n\u0261z\u01d0\u3000t\u012bn\u0261shu\u014d\u3000le\u3000zh&egrave;\u3000ji&agrave;n\u3000sh&igrave;\uff0c\u0261\u01cenk\u01cei\u3000de\u3000shu\u014d\uff1aw\u01d2\u3000zh\u01d0\u3000p&iacute;n\u0261\u3000y&aacute;nc&iacute;\u3000p&agrave;ndu&agrave;n \u3000r&eacute;n\u3000p\u01d0nzh&igrave;\u3000n&eacute;n\u0261l&igrave;\u3000de\u3000h\u01ceohu&agrave;i\uff0cji&eacute;\u0261u\u01d2\u3000du&igrave;\u3000Z\u01cei\u3000Y\u01d4\u3000de\u3000p&agrave;ndu&agrave;n\u3000ji&ugrave;\u3000cu&ograve;\u3000le\uff1bw\u01d2 \u3000zh\u01d0\u3000p&iacute;n\u0261\u3000xi&agrave;n\u0261m&agrave;o\u3000p&agrave;ndu&agrave;n\u3000r&eacute;n\u3000p\u01d0nzh&igrave;\u3000n&eacute;n\u0261l&igrave;\u3000de\u3000h\u01ceohu&agrave;i\uff0cji&eacute;\u0261u\u01d2\u3000du&igrave;\u3000 T&aacute;nt&aacute;i\u3000Mi&egrave;m&iacute;n\u0261\u3000de\u3000p&agrave;ndu&agrave;n\u3000y&ograve;u\u3000cu&ograve;\u3000le\u3002\u5b54\u5b50\u542c\u8bf4\u4e86\u8fd9\u4ef6\u4e8b\uff0c\u611f\u6168\u5730\u8bf4\uff1a\u6211\u53ea\u51ed\u8a00\u8f9e\u5224\u65ad\u4eba\u54c1\u8d28\u80fd\u529b\u7684\u597d\u574f\uff0c\u7ed3\u679c\u5bf9\u5bb0\u4e88 \u7684\u5224\u65ad\u5c31\u9519\u4e86\uff1b\u6211\u53ea\u51ed\u76f8\u8c8c\u5224\u65ad\u4eba\u54c1\u8d28\u80fd\u529b\u7684\u597d\u574f\uff0c\u7ed3\u679c\u5bf9\u6fb9\u53f0\u706d\u660e\u7684\u5224\u65ad\u53c8\u9519\u4e86\u3002<\/p>\n<\/div>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-579508509\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&rdquo;\u4ee5\u8c8c\u53d6\u4eba&ldquo;\u7684\u5178\u6545 &nbsp; &nbsp;K\u01d2n\u0261z\u01d0\u3000y\u01d2u\u3000x\u01d4x\u01d4\uff0ddu\u014ddu\u014d\u3000d&igrave;z\u01d0\uff0cq&iacute;zh\u014dn\u0261\u3000y\u01d2u\u3000y\u012b\u3000\u0261&egrave;\u3000m&iacute;n\u0261\u3000ji&agrave;o\u3000Z\u01cei-Y\u01d4\u3000de\uff0ch\u011bn\u3000 sh&igrave;\u3000n&eacute;n\u0261shu\u014dhu&igrave;d&agrave;o\u3002T\u0101\u3000k\u0101ish\u01d0\u3000\u0261\u011bi\u3000K\u01d2n\u0261z\u01d0\u3000de\u3000y&igrave;nxi&agrave;n\u0261\u3000b&ugrave;cu&ograve;\uff0cd&agrave;n\u3000h&ograve;ul&aacute;i\u3000 ji&agrave;nji&agrave;n\u3000de\u3000l&ograve;uch\u016b\u3000le\u3000b\u011bnxi&agrave;n\u0261\uff1aj&igrave;\u3000w&uacute;\u3000r&eacute;nd&eacute;\u3000y&ograve;u\u3000sh&iacute;f\u0113n\u3000l\u01cendu&ograve;\uff1bd&agrave;\u3000b&aacute;iti\u0101n\u3000 b&ugrave;\u3000d&uacute;sh\u016b\u3000t\u012bn\u0261ji\u01cen\u0261\uff0ct\u01cen\u0261\u3000z&agrave;i\u3000chu&aacute;n\u0261\u3000sh&agrave;n\u0261\u3000shu&igrave;\u3000d&agrave;ji&agrave;o\u3002W&egrave;ic\u01d0\uff0cK\u01d2n\u0261z\u01d0\u3000m&agrave;\u3000t\u0101\u3000 sh&igrave;\u3000xi\u01d4m&ugrave;b&ugrave;k\u011bdi\u0101o.<br \/>\n  \u5b54\u5b50\u6709\u8bb8\u8bb8\u591a\u591a\u5f1f\u5b50\uff0c\u5176\u4e2d\u6709\u4e00\u4e2a\u540d\u53eb\u5bb0\u4e88\u7684\uff0c\u5f88\u662f\u80fd\u8bf4\u4f1a\u9053\u3002\u4ed6\u5f00\u59cb\u7ed9\u5b54\u5b50\u7684\u5370\u8c61\u4e0d\u9519\uff0c\u4f46\u540e\u6765\u6e10\u6e10\u5730\u9732\u51fa\u4e86\u672c\u76f8\uff1a\u65e2\u65e0\u4ec1\u5fb7\u53c8\u5341\u5206\u61d2\u60f0\uff1b\u5927\u767d\u5929\u4e0d\u8bfb\u4e66\u542c\u8bb2\uff0c\u8eba\u5728\u5e8a\u4e0a\u7761\u5927\u89c9\u3002\u4e3a\u6b64\uff0c\u5b54\u5b50\u9a82\u4ed6\u662f\u673d\u6728\u4e0d\u53ef\u96d5\u3002<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2841,4],"tags":[57,720,71],"class_list":["post-7320","post","type-post","status-publish","format-standard","hentry","category-chinese-language-vocabulary","category-chinese-words-phrases","tag-chinese-language","tag-chinese-language-vocabulary","tag-vocabulary"],"views":277,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/7320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/comments?post=7320"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/posts\/7320\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/media?parent=7320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/categories?post=7320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/my\/wp-json\/wp\/v2\/tags?post=7320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}