{"id":1489,"count":4,"description":"","link":"https:\/\/chinesemoment.com\/th\/tag\/chinese-adjectives\/","name":"chinese adjectives","slug":"chinese-adjectives","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/th\/wp-json\/wp\/v2\/tags\/1489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chinesemoment.com\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chinesemoment.com\/th\/wp-json\/wp\/v2\/posts?tags=1489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}