{"id":14962,"date":"2019-08-28T20:17:32","date_gmt":"2019-08-28T20:17:32","guid":{"rendered":"http:\/\/chinesemoment.com\/spoken-chinese\/the-business-chinese-900-words311-320\/"},"modified":"2019-08-28T20:17:32","modified_gmt":"2019-08-28T20:17:32","slug":"the-business-chinese-900-words311-320","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/vi\/the-business-chinese-900-words311-320\/","title":{"rendered":"The business Chinese 900 words\uff08311-320\uff09"},"content":{"rendered":"<p style=\"text-align: center\">\n<p><div>311.There is a change we have to make in the order.<\/div>\n<\/p>\n<p><div>d&igrave;n\u0261d\u0101nzh\u014dn\u0261 y\u01d2uy&iacute;ch&ugrave; x\u016by&agrave;o xi\u016b\u0261\u01cei<\/div>\n<div>311.\u8ba2\u5355\u4e2d\u6709\u4e00\u5904\u9700\u8981\u4fee\u6539\u3002<\/div>\n<\/p>\n<p><div>312.We require that transshipment be allowed.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n y\u0101oqi&uacute; y\u01d4nx\u01d4 zhu\u01cenchu&aacute;n<\/div>\n<div>312.\u6211\u4eec\u8981\u6c42\u5141\u8bb8\u8f6c\u8239\u3002<\/div>\n<\/p>\n<p><div>313.When can you make shipment carefully?<\/div>\n<\/p>\n<p><div>n\u01d0m&eacute;n sh&eacute;nme sh&iacute;h&ograve;u zhu\u0101n\u0261chu&aacute;n<\/div>\n<div>313.\u4f60\u4eec\u4ec0\u4e48\u65f6\u5019\u88c5\u8239\uff1f<\/div>\n<\/p>\n<p><div>314.We&#39;ll get the goods dispatched within the stipulated time.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n ji\u0101n\u0261&agrave;n \u0261u\u012bd&igrave;n\u0261de sh&iacute;ji\u0101n f\u0101hu&ograve;<\/div>\n<div>314.\u6211\u4eec\u5c06\u6309\u89c4\u5b9a\u7684\u65f6\u95f4\u53d1\u8d27\u3002<\/div>\n<\/p>\n<p><div>315.When can you make the balace shipment?<\/div>\n<\/p>\n<p><div>n\u01d0m&eacute;n h&eacute;sh&iacute; k\u011by\u01d0 f\u0101 y&uacute;xi&agrave;dehu&ograve; ne<\/div>\n<div>315.\u4f60\u4eec\u4f55\u65f6\u53ef\u4ee5\u53d1\u4f59\u4e0b\u7684\u8d27\u5462\uff1f<\/div>\n<\/p>\n<p><div>316.I wonder if you could ship the order as soon as possible\uff1f<\/div>\n<\/p>\n<p><div>b&ugrave;zh\u012bd&agrave;o n&eacute;n\u0261f\u01d2u j\u01d0nku&agrave;i zhu\u0101n\u0261y&ugrave;n d&igrave;n\u0261hu&ograve;<\/div>\n<div>316.\u4e0d\u77e5\u9053\u80fd\u5426\u5c3d\u5feb\u88c5\u8fd0\u8ba2\u8d27\uff1f<\/div>\n<\/p>\n<p><div>317.Let&#39;s disscuss about the mode of transportation.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n t\u01ceol&ugrave;n y&iacute;xi&agrave; y&ugrave;nsh\u016bf\u0101n\u0261sh&igrave; b\u0251<\/div>\n<div>317.\u6211\u4eec\u8ba8\u8bba\u4e00\u4e0b\u8fd0\u8f93\u65b9\u5f0f\u5427\u3002<\/div>\n<\/p>\n<p><div>318.What mode of transportation do you suggest we use?<\/div>\n<\/p>\n<p><div>n\u01d0ji&agrave;ny&igrave; w\u01d2m&eacute;n y&ograve;n\u0261sh&eacute;nme y&ugrave;nsh\u016bf\u0101n\u0261sh&igrave; ne<\/div>\n<div>318.\u4f60\u5efa\u8bae\u6211\u4eec\u7528\u4ec0\u4e48\u8fd0\u8f93\u65b9\u5f0f\u5462\uff1f<\/div>\n<\/p>\n<p><div>319.What sort of delivery periods did you have in mind?<\/div>\n<\/p>\n<p><div>n\u01d0su\u01d2 d&agrave;su&agrave;nde sh&igrave; n\u01cey&igrave;zh\u01d2n\u0261 f\u0101hu&ograve;q\u012b<\/div>\n<div>319.\u4f60\u6240\u6253\u7b97\u7684\u662f\u54ea\u4e00\u79cd\u53d1\u8d27\u671f\uff1f<\/div>\n<\/p>\n<p><div>320.Please ensure that we&#39;ll get tight shipping documents before the arrival of the goods.<\/div>\n<\/p>\n<p><div>q\u01d0n\u0261 qu&egrave;b\u01ceo z&agrave;i hu&ograve;w&ugrave; d&agrave;od&aacute;qi&aacute;n w\u01d2f\u0101n\u0261 k\u011bn&aacute;d&agrave;o zh&egrave;n\u0261qu&egrave;de zhu\u0101n\u0261chu&aacute;n d\u0101nj&ugrave;<\/div>\n<div>320.\u8bf7\u786e\u4fdd\u5728\u8d27\u7269\u5230\u8fbe\u524d\u6211\u65b9\u53ef\u62ff\u5230\u6b63\u786e\u7684\u88c5\u8239\u5355\u636e\u3002<\/div><\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-1791068730\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>311.There is a change we have to make in the order.  \td&igrave;n\u0261d\u0101nzh\u014dn\u0261 y\u01d2uy&iacute;ch&ugrave; x\u016by&agrave;o xi\u016b\u0261\u01cei311.\u8ba2\u5355\u4e2d\u6709\u4e00\u5904\u9700\u8981\u4fee\u6539\u3002<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2874,2853],"tags":[42],"class_list":["post-14962","post","type-post","status-publish","format-standard","hentry","category-speaking","category-spoken-chinese","tag-business-chinese"],"views":178,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts\/14962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/comments?post=14962"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts\/14962\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/media?parent=14962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/categories?post=14962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/tags?post=14962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}