{"id":14982,"date":"2019-08-29T16:44:59","date_gmt":"2019-08-29T16:44:59","guid":{"rendered":"http:\/\/chinesemoment.com\/spoken-chinese\/the-business-chinese-900-words511-520\/"},"modified":"2019-08-29T16:44:59","modified_gmt":"2019-08-29T16:44:59","slug":"the-business-chinese-900-words511-520","status":"publish","type":"post","link":"https:\/\/chinesemoment.com\/vi\/the-business-chinese-900-words511-520\/","title":{"rendered":"The business Chinese 900 words\uff08511-520\uff09"},"content":{"rendered":"<p style=\"text-align: center\">\n<p><div>511 We really can&#39;t discount the price more than six percent.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n zh\u0113nde w&uacute;f\u01cet&iacute;\u0261\u014dn\u0261 ch\u0101o\u0261u&ograve; b\u01ceif\u0113nzh\u012bli&ugrave; de zh&eacute;k&ograve;u<\/div>\n<div>511.\u6211\u4eec\u771f\u7684\u65e0\u6cd5\u63d0\u4f9b\u8d85\u8fc76%\u7684\u6298\u6263\u3002<\/div>\n<\/p>\n<p><div>512 A discount of six percent is all that I&#39;m authorized to offer you.<\/div>\n<\/p>\n<p><div>b\u01ceif\u0113nzh\u012bli&ugrave; de zh&eacute;k&ograve;u sh&igrave;w\u01d2 qu&aacute;nxi&agrave;nn&egrave;i su\u01d2n&eacute;n\u0261 \u0261\u011bin\u01d0de<\/div>\n<div>512.6%\u7684\u6298\u6263\u662f\u6211\u6743\u9650\u5185\u6240\u80fd\u7ed9\u4f60\u7684\u3002<\/div>\n<\/p>\n<p><div>513 What sort of guarantee do you offer on your product?<\/div>\n<\/p>\n<p><div>n\u01d0m&eacute;n t&iacute;\u0261\u014dn\u0261 sh&eacute;nmey&agrave;n\u0261de ch\u01cenp\u01d0nb\u01ceozh&egrave;n\u0261 ne<\/div>\n<div>513.\u4f60\u4eec\u63d0\u4f9b\u4ec0\u4e48\u6837\u7684\u4ea7\u54c1\u4fdd\u8bc1\u5462\uff1f<\/div>\n<\/p>\n<p><div>514 A standard one. Replacement during the first year if all rules for proper use have been followed.<\/div>\n<\/p>\n<p><div>y\u01d2uy&iacute;\u0261e yu&aacute;nz&eacute; r&uacute;\u0261u\u01d2 z&agrave;iy&igrave;ni&aacute;nn&egrave;i f&uacute;h&eacute;\u0261&egrave;zh\u01d2n\u0261 sh\u01d0y&ograve;n\u0261\u0261u\u012bd&igrave;n\u0261 ji&ugrave;k\u011b \u0261\u0113n\u0261hu&agrave;n<\/div>\n<div>514.\u6709\u4e00\u4e2a\u539f\u5219\uff0c\u5982\u679c\u5728\u4e00\u5e74\u5185\u7b26\u5408\u5404\u79cd\u4f7f\u7528\u89c4\u5b9a\uff0c\u5c31\u53ef\u66f4\u6362\u3002<\/div>\n<\/p>\n<p><div>515 We offer a life-time guarantee.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n t&iacute;\u0261\u014dn\u0261 y\u01d2n\u0261ji\u01d4 b\u01ceozh&egrave;n\u0261<\/div>\n<div>515.\u6211\u4eec\u63d0\u4f9b\u6c38\u4e45\u4fdd\u8bc1\u3002<\/div>\n<\/p>\n<p><div>516 We have an extended warranty available at extra cost.<\/div>\n<\/p>\n<p><div>du&igrave;y&uacute; &eacute;w&agrave;i ji&agrave;qi&aacute;n w\u01d2m&eacute;n y\u01d2uji&agrave;och&aacute;n\u0261de b\u01ceozh&egrave;n\u0261 q\u012bxi&agrave;n<\/div>\n<div>516.\u5bf9\u4e8e\u989d\u5916\u4ef7\u94b1\u6211\u4eec\u6709\u8f83\u957f\u7684\u4fdd\u8bc1\u671f\u9650\u3002<\/div>\n<\/p>\n<p><div>517 Our guarantee covers maintenance for both parts and labor.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;nde b\u01ceozh&egrave;n\u0261sh&igrave; b\u0101oku&ograve; \u0261\u0113n\u0261hu&agrave;nl&iacute;n\u0261ji&agrave;n h&eacute; mi\u01cenf&egrave;ib\u01ceoy\u01cen\u0261<\/div>\n<div>517.\u6211\u4eec\u7684\u4fdd\u8bc1\u662f\u5305\u62ec\u66f4\u6362\u96f6\u4ef6\u548c\u514d\u8d39\u4fdd\u517b\u3002<\/div>\n<\/p>\n<p><div>518 Tell us about your post-purchase servicing.<\/div>\n<\/p>\n<p><div>\u0261&agrave;os&ugrave; w\u01d2m&eacute;n y\u01d2u\u0261u\u0101n n\u01d0m&eacute;n sh&ograve;uh&ograve;uf&uacute;w&ugrave; de q&iacute;n\u0261ku&agrave;n\u0261<\/div>\n<div>518.\u544a\u8bc9\u6211\u4eec\u6709\u5173\u4f60\u4eec\u552e\u540e\u670d\u52a1\u7684\u60c5\u51b5\u3002<\/div>\n<\/p>\n<p><div>519 We use service centers at major stores. They ship goods back to our national service center for repairs.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;n c\u01ceiy&ograve;n\u0261 d&agrave;di&agrave;n f&uacute;w&ugrave;zh\u014dn\u0261x\u012bn&nbsp;t\u0101men k\u011bb\u01cech\u01cenp\u01d0n y&ugrave;ns&ograve;n\u0261d&agrave;o w\u01d2m&eacute;nde \u0261u&oacute;n&egrave;i f&uacute;w&ugrave;zh\u014dn\u0261x\u012bn w&eacute;ixi\u016b<\/div>\n<div>519.\u6211\u4eec\u91c7\u7528\u5927\u5e97\u670d\u52a1\u4e2d\u5fc3\uff0c\u4ed6\u4eec\u53ef\u628a\u4ea7\u54c1\u8fd0\u9001\u5230\u6211\u4eec\u7684\u56fd\u5185\u670d\u52a1\u4e2d\u5fc3\u7ef4\u4fee\u3002<\/div>\n<\/p>\n<p><div>520 We have a toll-free number for customers to call.<\/div>\n<\/p>\n<p><div>w\u01d2m&eacute;ndu&igrave; \u0261&ugrave;k&egrave; t&iacute;\u0261\u014dn\u0261 mi\u01cenf&egrave;i f&uacute;w&ugrave; di&agrave;nhu&agrave;<\/div>\n<div>520.\u6211\u4eec\u5bf9\u987e\u5ba2\u63d0\u4f9b\u514d\u8d39\u670d\u52a1\u7535\u8bdd\u3002<\/div><\/p>\n<div class=\"chine-tie-zi-nei-rong-zhi-hou\" id=\"chine-2379942157\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-1889418300638825\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-1889418300638825\" \ndata-ad-slot=\"7273022922\" \ndata-ad-layout-key=\"-gw-3+1f-3d+2z\"\ndata-ad-format=\"fluid\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>511 We really can&#39;t discount the price more than six percent.  \tw\u01d2m&eacute;n zh\u0113nde w&uacute;f\u01cet&iacute;\u0261\u014dn\u0261 ch\u0101o\u0261u&ograve; b\u01ceif\u0113nzh\u012bli&ugrave; de zh&eacute;k&ograve;u511.\u6211\u4eec\u771f\u7684\u65e0\u6cd5\u63d0\u4f9b\u8d85\u8fc76%\u7684\u6298\u6263\u3002<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2874,2853],"tags":[42],"class_list":["post-14982","post","type-post","status-publish","format-standard","hentry","category-speaking","category-spoken-chinese","tag-business-chinese"],"views":174,"_links":{"self":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts\/14982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/comments?post=14982"}],"version-history":[{"count":0,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/posts\/14982\/revisions"}],"wp:attachment":[{"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/media?parent=14982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/categories?post=14982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemoment.com\/vi\/wp-json\/wp\/v2\/tags?post=14982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}